{"id":6843,"date":"2021-02-10T15:07:26","date_gmt":"2021-02-10T18:07:26","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?post_type=lp_course&#038;p=6843"},"modified":"2024-12-03T19:32:00","modified_gmt":"2024-12-03T22:32:00","slug":"coaching-ejecutivo","status":"publish","type":"lp_course","link":"https:\/\/pachapulai.com.ar\/encuentros\/formacion\/coaching-ejecutivo\/","title":{"rendered":"Coaching Ejecutivo"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Coaching Ejecutivo<\/strong><\/p>\n<p><span class=\"text_line\" data-position=\"5:4:0:0:0\" data-endposition=\"5:4:11:5:0\" data-complex=\"0\">El coaching ejecutivo es un m\u00e9todo de acompa\u00f1amiento que efect\u00faa un profe<\/span><span class=\"text_line\" data-position=\"5:4:11:5:0\" data-endposition=\"5:4:23:0:0\" data-complex=\"0\">sional debidamente entrenado para ello \u2014el coach ejecutivo\u2014 a un<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span><\/span><span class=\"text_line\" data-position=\"5:4:23:0:0\" data-endposition=\"5:4:36:4:0\" data-complex=\"0\">gerente, un ejecutivo o el funcionario de una empresa o instituci\u00f3n, con la fina<\/span><span class=\"text_line\" data-position=\"5:4:36:4:0\" data-endposition=\"5:4:49:0:0\" data-complex=\"0\">lidad de que desarrolle las competencias necesarias para su cargo y alcance los<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span><\/span><span class=\"text_line\" data-position=\"5:4:49:0:0\" data-endposition=\"5:4:61:3:0\" data-complex=\"0\">resultados profesionales o de negocio que le han sido asignados. Este espacio pro<\/span><span class=\"text_line\" data-position=\"5:4:61:3:0\" data-endposition=\"5:4:74:0:0\" data-complex=\"0\">porciona una metodolog\u00eda, un modelo y las herramientas para el ejercicio de esta<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span><\/span><span class=\"text_line\" data-position=\"5:4:74:0:0\" data-endposition=\"5:5:0:0:0\" data-complex=\"0\">pr\u00e1ctica. El coach no sugiere, no resuelve<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>los problemas del otro, no toma decisiones por el coachee. Por el contrario, se espera que un gerente haga justamente todo eso. Si un gerente antes de sugerir,<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>resolver problemas o tomar decisiones, escucha y pregunta buscando que el colaborador encuentre sus propias respuestas, estar\u00e1 promoviendo el desarrollo de<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>sus colaboradores a trav\u00e9s de herramientas de coaching como la escucha activa y<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>la pregunta como parte de un sistema de gesti\u00f3n. Sin embargo, si el tiempo apremia, la necesidad es inmediata o el colaborador no<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>encuentra f\u00e1cilmente las respuestas, se espera que el gerente d\u00e9 las respuestas y<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>pase a la acci\u00f3n. Como se puede observar, un gerente que usa herramientas de coaching estar\u00e1 promoviendo el aprendizaje de su colaborador apoy\u00e1ndole a desarrollar nuevas y mejores pr\u00e1cticas. Le ayudar\u00e1 a tomar conciencia de sus creencias<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>limitantes promoviendo que se declare voluntariamente responsable, dise\u00f1e un<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>plan de acci\u00f3n de mejora o transformaci\u00f3n con indicadores de medici\u00f3n, metas y<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>con una fecha de la pr\u00f3xima reuni\u00f3n para conversar de los avances y resultados.<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>Como se puede observar, el coaching es una vocaci\u00f3n de servicio, coaching es el<span data-selectable=\"0\" data-singlespace=\"1\" data-lineend=\"1\">\u00a0<\/span>liderazgo basado en el servicio y el desarrollo de los dem\u00e1s.<\/span><\/p>\n<p>Aunque las posibilidades de \u00e9xito de un proceso de coaching dependen en gran parte de la voluntad de cambio, aprendizaje y mejora de nuestros clientes, no podemos obviar que el acierto de nuestra intervenci\u00f3n como coaches es parte de esta clave para el \u00e9xito. En este sentido, consideramos la posibilidad de compartir con el resto de la comunidad de coaches nuestros conocimientos y nuestra experiencia para enriquecernos como profesionales, lograr procesos de coaching exitosos y aumentar el prestigio de nuestra profesi\u00f3n.<br \/>\nLa competencia y la excelencia profesional de los coaches son claves para garantizar la sostenibilidad, la visibilidad y el reconocimiento de nuestra profesi\u00f3n, por lo cual consideramos b\u00e1sico ponernos en valor, compartir conocimientos y experiencias para nutrirnos mutuamente y, en definitiva, ser mejores. Y si logramos ser mejores coaches y nuestros procesos de coaching realmente facilitan el logro de objetivos, el cambio y la mejora de nuestros clientes\u2026, nuestra sociedad tambi\u00e9n ser\u00e1 mejor.<br \/>\nConfiamos en que este espacio resulte de alg\u00fan modo \u00fatil e inspirador, del mismo modo que otros autores han sido fuente de inspiraci\u00f3n para nosotros y puedan disfrutarlo al m\u00e1ximo tambi\u00e9n.<\/p>\n<p><strong>Entregamos en Uniendo Ra\u00edces el Aval del absoluto Compromiso de Pacha Pulai Terapias Conscientes y Uniendo Ra\u00edces de que alcancen este T\u00edtulo tan a\u00f1orado por todos : La Paz para ustedes en su Ser y como Facilitadores para ser Camino y Herramienta \u00datil de otras personas que lleguen, buscando lo mismo. \u00a0Es para todo p\u00fablico en general que desee comunicar\u00a0 desde el amor, la creatividad que sale de nuestro Ser Superior y la responsabilidad hacia quienes dirijamos el conocimiento adquirido, sobre todo a nosotros mismos.<\/strong><\/p>\n<p><strong>El T\u00edtulo que se alcanza ninguna Instituci\u00f3n puede Avalarlo o Certificarlo, y es el de un&#8221; Ser Humano Completo, \u00cdntegro y lleno de Amor.&#8221;<\/strong><\/p>\n<p><strong>Nuestra Misi\u00f3n en Uniendo Ra\u00edces es acompa\u00f1ar a las personas para que se reconozcan en su Ser,<\/strong><\/p>\n<p><strong>La Visi\u00f3n: Aportar bienestar a la humanidad.<\/strong><\/p>\n<p><strong>Nuestros Valores: Servicio, Alegr\u00eda, Compromiso, Trabajo en Equipo, Amorosidad, Pasi\u00f3n, Posibilidad e Integridad.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Adriana Lampa<\/strong><\/p>\n<p><strong>Directora de Pacha Pulai Terapias Conscientes<\/strong><\/p>\n<p><strong>DIPLOMATURA, definida como un Programa de Estudios destinado al perfeccionamiento, actualizaci\u00f3n, capacitaci\u00f3n, entrenamiento y\/o formaci\u00f3n ampliamente de sus asistentes, en una tem\u00e1tica espec\u00edfica relacionada con los campos de inter\u00e9s.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><img decoding=\"async\" class=\"alignnone wp-image-6002 lazyload\" data-src=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/2021\/01\/Marca-de-Agua-300x285.jpg\" alt=\"\" width=\"234\" height=\"222\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 234px; --smush-placeholder-aspect-ratio: 234\/222;\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coaching Ejecutivo El coaching ejecutivo es un m\u00e9todo de acompa\u00f1amiento que efect\u00faa un profesional debidamente entrenado para ello \u2014el coach [&hellip;]<\/p>\n","protected":false},"author":20,"featured_media":18398,"comment_status":"closed","ping_status":"closed","template":"","course_category":[37],"course_tag":[],"class_list":["post-6843","lp_course","type-lp_course","status-publish","has-post-thumbnail","hentry","course_category-uniendo-caminos","course"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/lp_course\/6843","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/lp_course"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/lp_course"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/20"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=6843"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/lp_course\/6843\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/18398"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=6843"}],"wp:term":[{"taxonomy":"course_category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/course_category?post=6843"},{"taxonomy":"course_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/course_tag?post=6843"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}