{"id":3470,"date":"2020-08-04T21:59:49","date_gmt":"2020-08-05T00:59:49","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=633"},"modified":"2020-12-31T11:11:35","modified_gmt":"2020-12-31T14:11:35","slug":"mandatos-familiares-dar-en-mano","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/mandatos-familiares-dar-en-mano\/","title":{"rendered":"Mandatos Familiares: Dar en mano"},"content":{"rendered":"\r\n<p class=\"has-text-align-left\"><strong>\u00bfMandatos Familiares escritos con sangre ? <\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\"><em><strong>Los verbos ocultos del \u00e1rbol geneal\u00f3gico y C\u00f3mo superar el deber -ser <\/strong><\/em><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Comida y ropaje. Dos met\u00e1foras de aquello que nos dan y nos calzamos sin chistar. &#8221; No te gusta la sopa, entonces dos platos&#8221;. De ni\u00f1os somos rehenes de la voluntad de nuestros mayores. Y de adultos, tambi\u00e9n. A menos que tomemos conciencia.<\/p>\r\n\r\n\r\n\r\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/nino-tomando-sopa.jpg\"><img decoding=\"async\" class=\"alignnone size-medium wp-image-3537 lazyload\" data-src=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/nino-tomando-sopa-254x300.jpg\" alt=\"Pacha Pulai\" width=\"254\" height=\"300\" data-srcset=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/nino-tomando-sopa-254x300.jpg 254w, https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/nino-tomando-sopa.jpg 410w\" data-sizes=\"(max-width: 254px) 100vw, 254px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 254px; --smush-placeholder-aspect-ratio: 254\/300;\" \/><\/a><\/figure>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">El ayer se est\u00e1 actualizando todo el tiempo cuando no ponemos cada ingrediente en su lugar, cuando las mezclas son incoherentes o el mal gusto se instala en el inconsciente .. y &#8230; dispara una alergia &#8230;<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">La narraci\u00f3n que cada grupo construye &#8221; se construye &#8220;funciona como alimento. Y en el mercado y las ferias de todas las aldeas se intercambian &#8211; como monedas &#8211; esos otros recursos vitales para continuar la especie: Los mandatos familiares.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Las abuelas lo sab\u00edan; sus madres les hab\u00edan traspasado ese saber y a ellas las madres de sus abuelas .. Hab\u00eda que saciar el hambre y dar identidad a cada miembro del clan. Y se hilvanaron las historias. En el origen de los tiempos y en el origen de cada familia, hay un relato fundante : un caldero y un fuego encendido.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">La joven con los bolsillos del delantal tintineando de semillas, los cantos del labrador; las voces de los cortesanos refugiados lejos de la ciudad para protegerse de la peste: todos cuentan un suceso inaugural. Y antes, mucho antes, fueron los mitos que rondaron a sus diosas y dioses por santuarios y or\u00e1culos, que los renacieron en canciones y poemas hasta que se gastaron y se rehicieron en carne y hueso, humanos.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Y en la infancia de todos los tiempos, la sangre, la leche y la canci\u00f3n de cuna acompa\u00f1aron con cuentos aquello que los mayores desearon para nosotros. \u00bf Cumplimos con esas expectativas ? \u00bf Aceptamos sin protestar el &#8221; traje &#8221; impuesto ? \u00bf Nos dolieron las botas de siete leguas o los zapatitos de cristal ? y , sin embargo, los seguimos usando ? \u00bfNos compramos el personaje que nos ofrecieron ?<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Ah\u00ed estamos, congelados en un arquetipo. Sin cuestionar, sin desobedecer los mandatos, sin preguntarnos por qu\u00e9 volvemos a caer siempre en el mismo &#8221; cuento &#8221; . Repetimos la historia. \u00bf Y si cambiamos el color del cristal para poder ver de nuevo lo viejo, sopesarlo, indagar sus efectos, revisar sus trampas, advertir las lealtades invisibles que nos atan a aquello a lo que ya no queremos responder ?<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\"><strong><em>Des &#8211; programar <\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Nos alimentaron con historias y seguimos creyendo que ser y hacer lo que somos y hacemos es lo que te &#8221; toca &#8220;. Sentimos miedo &lt;&lt; pero seguimos adelante &gt;&gt; ante el peligro de atravesar el bosque, cuando nos cargan una cesta de tortas para la abuelita, o nos esforzamos para mantenernos siempre j\u00f3venes y hermosas ( para que el espejito nos diga lo que queremos o\u00edr, lo que ellos quieren ver .. ).<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\"><strong><em>Mandato quiere decir : Dar en mano <\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p>Grano a grano se forman las playas, \/ y luego viene el viento y las revuelve borrando las pisadas y los nombres.\/ Sin hijo, ni \u00e1rbol ni libro.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Ser. Tener hijos. Deber. Plantar \u00e1rboles. Escribir libros. Obedecer. Tener \u00e1rboles. Plantar libros. Escribir hijos. No ser. Deber ser&#8230; \u00a1Cu\u00e1nta exigencia en ese pasamanos que implica llegar a ocupar un nuevo eslab\u00f3n en la transmisi\u00f3n generacional!<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Cumplir un mandato es aceptar razones oscuras que desconocemos, pero que nos inducen a dar respuesta. Recibir un mandato es o\u00edr una orden, una expectativa de otros sobre nosotros. A veces con mayor claridad y otras con escaso entendimiento. Muchas veces es cumplir &#8211; sin analizar ni pensar &#8211; aquello que nos aguarda como &#8221; la misi\u00f3n que tenemos en la vida &#8221; .<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Decimos que un mandato es un precepto mudo, una prescripci\u00f3n sorda, un bando que se ha colgado sin remache a la vista: est\u00e1 pegado sin chinches ni clavos a la estructura de un grupo familiar, por eso tiene valor de enigma y por eso estamos tratamos toda la vida de entenderlo para complacer, sin comprender. Como en un laberinto y con los ojos vendados. Qu\u00e9 tarea dif\u00edcil &#8230;<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">No se dicen a boca de jarro y a todas las luces, no se expresan con claridad y buen tono, no se conocen porque fueron claramente explicitados : \u00a1 Hay que adivinarlos ! Una tarea imposible &#8230; Los mandatos constituyen una suerte de disposici\u00f3n que se escribe con la sangre del clan y que se oye como si se gritara, pero es un mensaje oculto y sinuoso; un decreto callado que emana de un superior &lt;&lt; al que tal vez no conocimos &gt;&gt; pero escuchamos ; un mandato determina las expectativas sobre el cumplimiento de esa orden familiar que cala hondo en los descendientes. Es un mandamiento casi en el sentido religioso o sagrado del t\u00e9rmino, que los m\u00e1s j\u00f3venes de una familia reciben de las manos de sus antepasados como una ofrenda ( muchas veces a modo de &#8221; caja de pandora &#8220;, es decir, algo imposible de soltar, algo que no terminamos de comprender.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Pasan los a\u00f1os, crecemos y sentimos una incomodidad que condiciona la libertad de actuar y de cambiar. Acotada la capacidad de elegir, seguimos a pie juntillas las \u00f3rdenes que nuestra sangre nos dicta. Fracasamos. Nos enfermamos. Repetimos el gui\u00f3n. Antes de entrar en este \u00e1rbol que nos pertenece, ya hab\u00edan usado la tinta tan especial ( espesa ), real, ( por contundente, no por azul, sino roja y estridente) y casi siempre con intenciones de mantener la lealtad para acular el trazo que identifica a los &#8220;nuestros &#8220;.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">La palabra mandato deriva del lat\u00edn manus ( mano) + dare (dar ) : hace referencia a un encargo que debe ser dado en mano. Conocemos otras palabras que se desprenden de esa misma idea madre, mano: mandamiento, mandado, manufactura, manuscrito, mando, manifestar ( hacer fiesta con las manos linda palabra, \u00bf verdad ?), emancipar ( salir de la posici\u00f3n de estar bajo la mano de otro o de su tutela), maniobrar ( obrar con la mano). Otra : Mantener, contracci\u00f3n de manu ( mano) + tenere (poder) : tener en la mano. De ah\u00ed : &#8220;no morder la mano de quien te da de comer&#8221; o expresiones como &#8221; pedir la mano &#8221; ,&#8221; aqu\u00ed mando yo &#8221; ( es decir, quien tiene el mando).<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">As\u00ed, se entiende por mandato un tipo de contrato mediante el cual el mandante conf\u00eda una gesti\u00f3n que debe ser cumplida por el mandatario. &#8221; Es un contrato consensual, bilateral, imperfecto, de buena fe y gratuito&#8221;, agrega la RAE, y nosotros completamos desde la psicolog\u00eda transgeneracional : Firmado con tinta invisible, la sangre. La sangre del \u00e1rbol.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Tambi\u00e9n, el t\u00e9rmino mandato alude al acto o instrumento en que consta la facultad que alguien da a otra persona para que en lugar suyo y represent\u00e1ndole pueda ejecutar algo. El destacado en cursiva subraya la idea de una expectativa personal (a nombre propio) para que otro la tome y desarrolle ( a cuenta ajena ) : los descendientes de ese linaje.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Como &#8220;una papa caliente&#8221; lo que se espera de cada miembro de la tribu pasa y quema, da otro salto y requema en las manos de la siguiente generaci\u00f3n, una y otra vez hasta que se aprende. Se repite porque no se ha tomado consciencia: el inconsciente vuelve sobre lo inacabado, lo irresuelto. Vuelve y se repite hasta que, en alguno de los tramos del recorrido generacional, alguien dice, \u00a1 basta !.<\/p>\r\n\r\n\r\n\r\n<p class=\"has-text-align-left\">Podemos aceptar unos condicionamientos y no otros, podemos llevarlos adelante por un tiempo y no por siempre : somos seres complejos y din\u00e1micos: la humanidad ha evolucionado justamente por el vaiv\u00e9n entre esas dos caracter\u00edsticas. Y si bien las culturas hacen que los sujetos manifiesten sus diferencias &lt;&lt; determinada posici\u00f3n en asuntos relativos al amor, la familia, los v\u00ednculos extra sangu\u00edneos, las relaciones que var\u00edan socio culturalmente, de un contexto a otro, como las creencias, los valores o los prejuicios &gt;&gt;, todos estamos gen\u00e9ticamente programados dentro de la especie a la cual pertenecemos.<\/p>\r\n\r\n\r\n\r\n<p><a href=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/escrito-en-sangre-17640193-1-1.jpg\"><img decoding=\"async\" class=\"alignnone size-full wp-image-3539 lazyload\" data-src=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/escrito-en-sangre-17640193-1-1.jpg\" alt=\"Pacha Pulai\" width=\"239\" height=\"160\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 239px; --smush-placeholder-aspect-ratio: 239\/160;\" \/><\/a><\/p>\r\n\r\n\r\n\r\n\r\n\r\n<p>Desarrollaremos durante todo el mes de agosto este tema tan apasionante para todos y veremos las respuestas y cambios que pueden darnos las Terapias de Constelaciones, Decodificaci\u00f3n Biol\u00f3gica y Di\u00e1logos con el Cuerpo.<\/p>\r\n<button class=\"simplefavorite-button has-count\" data-postid=\"3470\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>\u00bfMandatos Familiares escritos con sangre ? Los verbos ocultos del \u00e1rbol geneal\u00f3gico y C\u00f3mo superar el deber -ser Comida y [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":3471,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3470","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/3470","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=3470"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/3470\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/3471"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=3470"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=3470"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=3470"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}