{"id":3508,"date":"2020-08-12T21:08:41","date_gmt":"2020-08-13T00:08:41","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=677"},"modified":"2020-12-31T11:11:03","modified_gmt":"2020-12-31T14:11:03","slug":"amor-y-desamor","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/amor-y-desamor\/","title":{"rendered":"Amor y Desamor"},"content":{"rendered":"\r\n<p><strong><em>Relacionarse, no relacionarse<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p><br \/>EL AMOR es un estado de conciencia en el que te sientes jubiloso, en<br \/>el que tu ser baila. Algo empieza a vibrar, a irradiar desde tu centro; algo<br \/>empieza a palpitar a tu alrededor. Empieza a llegar a la gente: puede<br \/>llegar a las mujeres, a los hombres, a las piedras, los \u00e1rboles y las<br \/>estrellas.<br \/>Cuando hablo del amor, me refiero a un amor que no es una relaci\u00f3n<br \/>sino un estado del ser. Recu\u00e9rdalo: siempre que empleo la palabra<br \/>\u00abamor\u00bb me refiero a un estado del ser, no a una relaci\u00f3n. La relaci\u00f3n no<br \/>es sino un aspecto secundario. Pero la idea que se suele tener del amor es<br \/>b\u00e1sicamente la relaci\u00f3n, y no se reduce a eso.<br \/>Necesitas las relaciones porque no puedes estar solo, porque a\u00fan no<br \/>eres capaz de meditar. La meditaci\u00f3n es imprescindible para que puedas<br \/>amar de verdad. Deber\u00edamos ser capaces de estar solos, completamente<br \/>solos, y felices. Entonces se puede amar. Entonces tu amor ya no es una<br \/>necesidad sino un compartir. Entonces compartir\u00e1s, y compartir es<br \/>maravilloso.<br \/>Pero lo que suele ocurrir en el mundo es lo siguiente: no tienes<br \/>amor, la persona a la que t\u00fa crees amar tampoco tiene amor en su ser, y<br \/>ambos os ped\u00eds amor mutuamente. \u00a1Dos mendigos mendig\u00e1ndose! De ah\u00ed<br \/>derivan el conflicto, la lucha, la continua pelea entre los amantes, por cosas triviales, absurdas. Pero as\u00ed y todo, no paran de pelearse.<br \/>La pelea de la que procede todo es que el marido piensa que no<br \/>recibe lo que tiene derecho a recibir, y lo mismo ocurre con la mujer. La<br \/>mujer piensa que la han enga\u00f1ado y otro tanto piensa el marido. \u00bfD\u00f3nde<br \/>est\u00e1 el amor? Nadie se molesta en dar, pero todos quieren recibir. Y si lo<br \/>que buscan todos es recibir, nadie lo recibe y todos se sienten perdidos,<br \/>vac\u00edos, tensos.<br \/>No existen cimientos, y has empezado a construir el templo por el<br \/>tejado. Se desmoronar\u00e1 en cualquier momento. Y sabes muy bien cu\u00e1ntas<br \/>veces se ha desmoronado tu amor, pero sigues haciendo lo mismo una y<br \/>otra vez.<br \/>\u00a1Vives en tal inconsciencia! No ves lo que le has estado haciendo a tu<br \/>vida y a la de los dem\u00e1s. Act\u00faas de una forma autom\u00e1tica, como un robot,<br \/>repitiendo las viejas pautas, sabiendo perfectamente que ya lo has hecho<br \/>antes. Y tambi\u00e9n sabes cu\u00e1l es el resultado, y en el fondo sabes que va a<br \/>pasar lo mismo, porque no hay ninguna diferencia. Te preparas para la<br \/>misma conclusi\u00f3n, el mismo desmoronamiento. Si puedes aprender algo<br \/>del fracaso en el amor, es ser m\u00e1s consciente, m\u00e1s meditativo. Y cuando<br \/>hablo de meditaci\u00f3n me refiero a la capacidad de ser feliz en soledad. Son<br \/>muy pocos los que pueden sentirse contentos sin raz\u00f3n alguna,<br \/>simplemente por estar sentados en silencio, felices. Los dem\u00e1s pensar\u00e1n<br \/>que est\u00e1s loco, porque la idea de la felicidad consiste en que proviene de<br \/>otra persona. Conoces a una mujer maravillosa, o a un hombre<br \/>maravilloso y te sientes feliz. \u00bfA solas en tu habitaci\u00f3n y tan contento, tan<br \/>feliz? \u00a1Debes de estar loco! La gente pensar\u00e1 que te has drogado, que<br \/>est\u00e1s colocado.<br \/>\u00a1Pues s\u00ed, la meditaci\u00f3n es el LSD definitivo! Supone liberar tus<br \/>propios poderes psicod\u00e9licos, desencadenar tu propio esplendor, que<br \/>estaba preso. Y te sientes tan feliz, tan jubiloso en tu ser, que no<br \/>necesitas ninguna relaci\u00f3n. Puedes relacionarte con la gente\u2026 y esa es<br \/>precisamente la diferencia entre relacionarse y una relaci\u00f3n.<br \/>La relaci\u00f3n es una cosa: te aferras a ella. Relacionarse es una<br \/>corriente, un movimiento, un proceso. Conoces a una persona, la quieres,<br \/>porque tienes tanto amor que ofrecer\u2026 y cuanto m\u00e1s das, m\u00e1s tienes.<br \/>Has de entender esta extra\u00f1a aritm\u00e9tica del amor, que cuanto m\u00e1s das,<br \/>m\u00e1s tienes, algo contrario a las leyes econ\u00f3micas del mundo exterior. Una<br \/>vez que lo hayas comprendido, si quieres recibir m\u00e1s amor y m\u00e1s alegr\u00eda,<br \/>das y compartes, y despu\u00e9s simplemente compartes. Y te sientes<br \/>agradecido a quienquiera que te permite compartir tu alegr\u00eda, con ella o<br \/>con \u00e9l. Pero no es una relaci\u00f3n; es como el fluir de un r\u00edo.<br \/>El r\u00edo pasa junto a un \u00e1rbol, le dice hola, lo nutre, le da agua\u2026 y<br \/>sigue su curso, su baile. No se aferra al r\u00edo. Y el r\u00edo no dice: \u00ab\u00bfAdonde<br \/>vas? \u00a1Estamos casados! Si pensabas abandonarme, \u00bfpor qu\u00e9 has bailado<br \/>as\u00ed a mi alrededor? \u00bfPor qu\u00e9 me has alentado?\u00bb No; el \u00e1rbol colma al r\u00edo<br \/>con sus flores, profundamente agradecido, y el r\u00edo sigue fluyendo. Llega el<br \/>viento y danza alrededor del \u00e1rbol y sigue corriendo. Y el \u00e1rbol le da su<br \/>fragancia al viento.<\/p>\r\n\r\n\r\n\r\n<p>En eso consiste relacionarse. Si la humanidad llega alg\u00fan d\u00eda a la<br \/>edad adulta, madura, as\u00ed ser\u00e1 el amor: personas que se conocen,<br \/>comparten, siguen andando, sin sentimiento de posesi\u00f3n, ni de<br \/>dominaci\u00f3n. En otro caso, el amor es simplemente una lucha de poder.<\/p>\r\n\r\n\r\n\r\n<p><strong><em>ALGUNOS ESCOLLOS<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p><br \/>La gente tiene miedo de la gran m\u00fasica, de la gran poes\u00eda, de la<br \/>intimidad profunda. Las historias amorosas de las personas son fortuitas.<br \/>No profundizan en el ser del otro porque tienen miedo, el temor a<br \/>reflejarse en el estanque del ser del otro. Y en ese estanque, en ese<br \/>espejo del ser del otro, si no te encuentras, si el espejo est\u00e1 vac\u00edo, si no<br \/>refleja nada, \u00bfentonces qu\u00e9?<\/p>\r\n\r\n\r\n\r\n<p><br \/><strong><em>La costumbre de la reacci\u00f3n<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p><br \/><strong><em>UNA REACCI\u00d3N<\/em><\/strong> procede del pasado, una respuesta del presente.<br \/>Reaccionas con formas del pasado. Alguien te insulta y el viejo mecanismo<br \/>se pone en funcionamiento. En el pasado, cuando te insultaban actuabas<br \/>de cierta manera, y ahora act\u00faas igual. No respondes a ese insulto y esa<br \/>persona, sino que repites una vieja costumbre. No has mirado a esa<br \/>persona y el nuevo insulto \u2014tiene un sabor distinto\u2014; funcionas como un<br \/>robot. Tienes cierto mecanismo en tu interior, aprietas el bot\u00f3n y dices:<br \/>\u00abEste hombre me ha insultado\u00bb y reaccionas. La reacci\u00f3n no es la situaci\u00f3n real, sino una proyecci\u00f3n. Has visto el pasado en ese hombre.<br \/><br \/><\/p>\r\n\r\n\r\n\r\n<p><strong><em>Apegados a la seguridad<\/em><\/strong><\/p>\r\n\r\n\r\n\r\n<p><br \/>NINGUNA RELACI\u00d3N es segura. No est\u00e1 en la naturaleza de las<br \/>relaciones que haya seguridad, y si existe alguna as\u00ed, perder\u00e1 todo su<br \/>atractivo. Por tanto, se trata de un problema para la mente. Si quieres<br \/>disfrutar de una relaci\u00f3n, tiene que ser insegura. Si se convierte en algo<br \/>seguro, completamente seguro, no puedes disfrutarla: pierde todo el<br \/>encanto, todo el atractivo. Como la mente no queda satisfecha ni con esto<br \/>ni con lo otro, est\u00e1 siempre en conflicto, en estado de caos. Necesita una<br \/>relaci\u00f3n viva y segura, pero es imposible, porque una persona viva o una<br \/>relaci\u00f3n viva o cualquier cosa viva ha de ser impredecible. No se puede<br \/>prever lo que va a ocurrir al momento siguiente. Y porque ese momento<br \/>es impredecible, es intenso.<br \/>Has de vivir ese momento con la mayor intensidad posible, porque<br \/>quiz\u00e1 no llegue otro momento. A lo mejor ya no est\u00e1s ah\u00ed, o el otro no<br \/>est\u00e1 ah\u00ed. O tal vez los dos est\u00e9is ah\u00ed, pero no la relaci\u00f3n. Quedan abiertas<br \/>todas las posibilidades. El futuro siempre est\u00e1 abierto; el pasado, siempre<br \/>cerrado. Y entre medias est\u00e1 el presente, un solo momento del presente,<br \/>siempre tembloroso, agitado. Pero as\u00ed es la vida. Temblar y agitarse<br \/>forman parte de la vida: la vacilaci\u00f3n, la oscuridad, la vaguedad.<br \/>El pasado est\u00e1 cerrado. Todo ha ocurrido y ya no se puede cambiar<br \/>nada, de modo que todo ha quedado cerrado. El futuro est\u00e1 abierto: no se<br \/>puede predecir nada. Y entre medias est\u00e1 el presente, con un pie en el<br \/>pasado y otro en el futuro. Por eso, la mente mantiene la dicotom\u00eda, una<br \/>divisi\u00f3n. Siempre est\u00e1 dividida, esquizofr\u00e9nica.<br \/>Has de entender que las cosas son as\u00ed y que no se puede hacer nada.<br \/>Si quieres mantener una relaci\u00f3n muy segura, tendr\u00e1s que amar a un<br \/>muerto, pero no lo disfrutar\u00e1s. Eso es lo que le ocurre a un amante<br \/>cuando pasa a marido: un marido es un amante muerto, como una esposa<br \/>es una amante muerta. El pasado lo es todo, y el pasado decide el futuro.<br \/>Si eres la esposa de alguien, no tienes futuro: el pasado seguir\u00e1<br \/>repiti\u00e9ndose, con todas las puertas cerradas. Si eres el marido de alguien<br \/>no tienes futuro; est\u00e1s confinado, en una prisi\u00f3n.<br \/>Se busca sin cesar la seguridad, pero cuando se encuentra resulta<br \/>aburrida. No hay m\u00e1s que ver las caras de los casados. Han encontrado la<br \/>tan deseada seguridad, y todo ha ido a parar a su cuenta corriente, las<br \/>leyes, y los abogados y los tribunales se encargar\u00e1n de que todo quede<br \/>asegurado. Pero se ha perdido todo el encanto, toda la poes\u00eda: ya no hay<br \/>romanticismo. Est\u00e1n muertos: se limitan a repetir el pasado, a vivir de<br \/>recuerdos.<br \/>No hay m\u00e1s que o\u00edr c\u00f3mo hablan los que est\u00e1n casados. La mujer<br \/>dice que su marido ya no la quiere como antes, y hablan de momentos<br \/>pasados, de su luna de miel y tal. \u00a1Qu\u00e9 tonter\u00eda! A\u00fan est\u00e1s viva. Este<br \/>momento puede ser una luna de miel. Este momento se puede vivir, pero<br \/>t\u00fa hablas del pasado e intentas repetirlo.<br \/>La seguridad jam\u00e1s satisface, y en la inseguridad hay miedo, miedo a<br \/>perder la relaci\u00f3n, pero eso forma parte del estar vivo. Todo puede<br \/>perderse, no hay nada cierto y por eso todo es tan hermoso. Y por eso no<br \/>puedes retrasar nada ni un solo momento: si deseas amar a una persona,<br \/>\u00e1mala aqu\u00ed y ahora. \u00c1mala, porque nadie sabe qu\u00e9 pasar\u00e1 dentro de un<br \/>momento. Dentro de un momento quiz\u00e1 no exista ninguna posibilidad para el amor, y te arrepentir\u00e1s el resto de tu vida. Podr\u00edas haber amado,<br \/>podr\u00edas haber vivido. Entonces te arrepentir\u00e1s, sentir\u00e1s remordimientos y<br \/>una profunda culpa, como si te hubieras suicidado.<br \/>La vida es incierta, y nadie puede cambiar esto. No hay forma de que<br \/>sea de otra manera. Y es bueno que nadie pueda hacerla segura, porque<br \/>entonces estar\u00eda muerta. La vida es fr\u00e1gil, delicada, y se interna<br \/>continuamente en lo desconocido: ah\u00ed reside su belleza. Hay que ser<br \/>valiente, aventurero, apostar para moverse con la vida. De modo que<br \/>apuesta. Vive este momento y v\u00edvelo plenamente. Dentro de un momento,<br \/>ya se ver\u00e1. Estar\u00e1s all\u00ed para abordarlo \u2014como estuviste en el pasado y lo<br \/>estar\u00e1s en el futuro\u2014 y ser\u00e1s m\u00e1s capaz porque tendr\u00e1s m\u00e1s experiencia.<br \/>Por tanto, no se trata de si el otro estar\u00e1 all\u00ed en el momento<br \/>siguiente, sino que, si est\u00e1 disponible para ti en este momento, \u00e1malo. No<br \/>desperdicies este momento pensando en el futuro y preocup\u00e1ndote por \u00e9l,<br \/>porque es una actitud suicida. No dediques ni un solo pensamiento al<br \/>futuro, porque no se puede hacer nada al respecto y es una completa<br \/>p\u00e9rdida de energ\u00eda. Ama a esta persona y que ella te ame.<br \/>As\u00ed lo veo yo: si vives el momento plenamente, existen todas las<br \/>posibilidades de que al momento siguiente la persona siga estando<br \/>disponible. Y digo que es posible: no puedo prometer nada. Pero hay m\u00e1s<br \/>posibilidades, porque el momento siguiente proceder\u00e1 del momento<br \/>presente. Si has amado a esa persona y se siente feliz y la relaci\u00f3n ha<br \/>sido una experiencia hermosa, un \u00e9xtasis, \u00bfpor qu\u00e9 iba a dejarte?<br \/>Si no dejas de preocuparte, la est\u00e1s obligando a dejarte. Y si has<br \/>desperdiciado este momento, el momento siguiente surgir\u00e1 de ese<br \/>desperdicio: estar\u00e1 podrido. As\u00ed es como puedes predecirte: siempre se<br \/>cumplen tus profec\u00edas. Al momento siguiente dices: \u00abYa dec\u00eda yo desde el<br \/>principio que esta relaci\u00f3n no durar\u00eda. Ahora queda demostrado.\u00bb<br \/>Entonces te sientes bien, en cierto modo; piensas que has sido listo y<br \/>previsor. En realidad has sido est\u00fapido, porque no es que hubieras<br \/>predicho nada. Has forzado el acontecimiento porque has desperdiciado el<br \/>tiempo y la oportunidad que se te hab\u00edan concedido. De modo que ama a<br \/>la persona y olv\u00eddate del futuro. D\u00e9jate de tonter\u00edas y no pienses en el<br \/>futuro. Si puedes amar, ama. Si no puedes, olvida a esa persona, busca a<br \/>otra, pero no pierdas el tiempo.<br \/>La cuesti\u00f3n no consiste en este amante o el otro, sino en el amor. El<br \/>amor satisface, y las personas son excusas. Pero todo depende de ti,<br \/>porque lo que hagas con una persona lo seguir\u00e1s haciendo con otra.<br \/>Si haces feliz a una persona, \u00bfpor qu\u00e9 habr\u00eda de dejarte? Pero si la<br \/>haces desdichada, \u00bfpor qu\u00e9 no habr\u00eda de dejarte? Si la haces desdichada,<br \/>\u00a1yo la ayudar\u00eda a que te dejara! Pero si la haces feliz, nadie puede<br \/>ayudarla a dejarte, porque no tendr\u00eda sentido: luchar\u00eda contra el mundo<br \/>entero por ti.<br \/>As\u00ed que s\u00e9 m\u00e1s feliz. Emplea el tiempo de que dispones, sin pensar<br \/>en el futuro; el presente es suficiente. Desde este mismo momento,<br \/>intenta vivir este momento. Emplea este momento en no preocuparte,<br \/>sino en vivir. Las peque\u00f1as cosas pueden ser muy hermosas. Querer un<br \/>poco, compartir un poco: eso es la vida.<\/p>\r\n<button class=\"simplefavorite-button has-count\" data-postid=\"3508\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>Relacionarse, no relacionarse EL AMOR es un estado de conciencia en el que te sientes jubiloso, enel que tu ser [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":3509,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-3508","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/3508","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=3508"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/3508\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/3509"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=3508"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=3508"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=3508"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}