{"id":4950,"date":"2020-09-27T15:45:12","date_gmt":"2020-09-27T18:45:12","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=4950"},"modified":"2020-12-29T15:02:38","modified_gmt":"2020-12-29T18:02:38","slug":"estaciones-del-alma","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/estaciones-del-alma\/","title":{"rendered":"Estaciones del Alma"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>La cueva<\/strong><\/p>\n<p>Tal como hemos se\u00f1alado anteriormente, cuando el alma llega al invierno busca un espacio donde refugiarse, similar a una cueva. En este lugar subterr\u00e1neo se tiene acceso a las profundidades y all\u00ed se puede establecer contacto con las fuerzas y los poderes interiores que luego salen al exterior.<br \/>\nEntrar en una cueva significa, psicol\u00f3gicamente, una b\u00fasqueda de protecci\u00f3n.<br \/>\nTambi\u00e9n implica la renuncia temporal a los afanes terrenales en busca de un sentido m\u00e1s trascendente de la vida.<br \/>\nEsta experiencia constituye un desaf\u00edo que, por una parte, conduce de vuelta al origen, al vientre materno, al \u00fatero, como lugar de contenci\u00f3n y seguridad. Y, por otra, implica enfrentarse a lo que permanece oculto de la propia personalidad, al misterioso<br \/>\nmundo del inconsciente.<br \/>\nSe dice que la cueva es tambi\u00e9n un s\u00edmbolo inici\u00e1tico, ya que desde \u00e9pocas muy antiguas este tipo de cavidades naturales han estado vinculadas a ritos de iniciaci\u00f3n. Ellas significan un viaje a las profundidades para enfrentarse a los peligros desconocidos que<br \/>\nall\u00ed se encuentran.<br \/>\nEn El Quijote de la Mancha, tambi\u00e9n se hace alusi\u00f3n a este concepto cuando el gu\u00eda que acompa\u00f1a a Don Quijote y a Sancho hasta la cueva le advierte: \u201cmire bien y especule con cien ojos lo que hay all\u00e1 dentro; quiz\u00e1s habr\u00e1 cosas que las ponga en el libro de mis Transformaciones\u201d. Haciendo referencia a que la exposici\u00f3n al peligro y a las pruebas inici\u00e1ticas tienen como fin transformar al que aspira a conocer los misterios de la vida.<br \/>\nLuego lo describe antes de traspasar el umbral en la entrada de la cueva que, no obstante es \u201cespaciosa y ancha\u201d, est\u00e1 llena de zarzas y de malezas \u201ctan espesas e intrincadas que de todo en todo la ciegan y encubren\u201d. Poniendo de manifiesto que el acceso a la cueva es amplio y pueden cruzar todos los que est\u00e9n dispuestos a usar su espada para abrirse camino eliminando los obst\u00e1culos \u2014las zarzas y malezas de la personalidad\u2014 que a veces ciegan a las personas y les impiden ver la realidad.<br \/>\nAl salir de la cueva Don Quijote dice a sus amigos: \u201cme hab\u00e9is quitado de la m\u00e1s sabrosa y agradable vida y vista que ning\u00fan humano ha visto ni pasado\u201d. Aun cuando Sancho le asegura que solo estuvo en la cueva poco m\u00e1s de una hora, \u00e9l afirma que al quedarse dormido pas\u00f3 a otro plano distinto del f\u00edsico en el cual vivi\u00f3 tres d\u00edas y tres noches. Durante ese tiempo descubri\u00f3 que \u201ctodos los contentos de esta vida pasan como sombra y sue\u00f1o, o se marchitan como la flor del campo\u201d. Y ahora sabe que la muerte no existe, pues viene del otro mundo y en el ha podido hablar con los muertos. En otros cuentos y leyendas tambi\u00e9n se describen cuevas y cavernas como lugares m\u00edsticos, donde nacen y se entierran dioses y h\u00e9roes. Asimismo, en numerosas tradiciones se dice que en ellas habitan diferentes seres mitol\u00f3gicos: gnomos, esp\u00edritus y dragones, guardianes de tesoros y de fuerzas demon\u00edacas. Estos relatos aluden al hecho de que en el fondo de las cuevas se encuentran aquellas entidades y fuerzas que tienen poder sobre nosotros, aunque a nivel consciente las desconocemos.<br \/>\nEl peligro de este proceso de autoconocimiento es quedarse atrapado en el. Es decir, aislarse del mundo, encerrarse en s\u00ed mismo y no poder salir de la cueva por temor a perder la aparente seguridad que brinda este espacio protegido. El lado positivo de esta experiencia es que permite encontrar las riquezas escondidas en el interior de cada uno y luego volver al mundo para compartir estos descubrimientos. Joseph Campbell, estudioso de los mitos y s\u00edmbolos de diversas culturas, lleg\u00f3 a esta misma conclusi\u00f3n al afirmar que: \u201cla cueva oscura donde temes entrar es donde est\u00e1 tu tesoro\u201d.<br \/>\nCuando nos encontramos en un tiempo de oscuridad, encerrados o paralizados en un estado emocional inconfortable, es importante preguntarse: \u00bfqu\u00e9 es lo que no queremos enfrentar? \u00bfA qu\u00e9 le tenemos miedo? \u00bfPor qu\u00e9 nos estamos aislando? \u00bfQu\u00e9 hemos descubierto de nosotros mismos en este espacio interior? \u00bfSomos receptivos a las se\u00f1ales que nos muestran la salida? \u00bfDeseamos correr el riesgo de exponernos a la realidad<br \/>\nexterior?<\/p>\n<p><strong>El invierno del alma<\/strong><br \/>\nLos per\u00edodos invernales son de soledad y desamparo, y surgen cuando el fr\u00edo llega al alma para recordarnos que somos fr\u00e1giles y vulnerables. Parad\u00f3jicamente, estos estados luz no nos llega. Son tiempos para viajar hacia adentro, buscando y recorriendo los rincones de la memoria. Es como entrar a un t\u00fanel que conduce a la zona de los misterios, para los cuales no tenemos explicaci\u00f3n. El anhelo es que el tr\u00e1nsito por esta estaci\u00f3n sea breve, porque es percibida como una experiencia dura que es preferible evitar para no enfrentar aquellos aspectos ocultos que asustan y muestran, en definitiva, la dualidad de la existencia.<br \/>\nEl alma entra en estos espacios generalmente despu\u00e9s de un per\u00edodo de oto\u00f1o, es decir, despu\u00e9s de una p\u00e9rdida o un cambio repentino que mueve el piso y altera la ruta trazada con anterioridad. Son momentos en que es necesario descansar para poder reorientarse. Por eso las etapas de duelo, por ejemplo, son tan necesarias. Replegarse por un tiempo, alejarse del ruido, dejar que las emociones decanten, son actitudes que favorecen la recuperaci\u00f3n del \u00e1nimo y la energ\u00eda que se requiere para retomar o reinventar un nuevo camino.<br \/>\nEn los vegetales se da un estado denominado \u201cletargo invernal\u201d que constituye un mecanismo de defensa ante el dif\u00edcil clima del invierno. Si durante esta estaci\u00f3n las plantas mantuvieran sus hojas verdes y vigorosas, se expondr\u00edan a la destrucci\u00f3n por causa de las heladas. Incluso podr\u00edan florecer anticipadamente y con el hielo las flores se perder\u00edan, poniendo en riesgo la reproducci\u00f3n de la especie.<br \/>\nCuriosamente, para salir del letargo las plantas necesitan tiempo y una cierta cantidad de fr\u00edo en torno a los 7\u00b0 C. Si en ese per\u00edodo las temperaturas se elevan sobre los 16\u00b0 C, en lugar de salir m\u00e1s pronto de ese estado se produce un retroceso porque la planta a\u00fan no est\u00e1 lista para pasar a la siguiente etapa. Cada especie tiene ciertas necesidades de fr\u00edo invernal y si no se cumplen las condiciones adecuadas para completarlas las consecuencias pueden ser muy negativas para la producci\u00f3n de frutos y para el desarrollo del \u00e1rbol.<br \/>\nAlgunos mam\u00edferos, entre ellos los osos, tambi\u00e9n experimentan un per\u00edodo de letargo conocido como hibernaci\u00f3n durante el cual se resguardan en sus cuevas, disminuyendo al m\u00ednimo su nivel de actividad y el ritmo de sus funciones metab\u00f3licas. Este mecanismo de preservaci\u00f3n les permite resistir las condiciones ambientales y ahorrar energ\u00eda mientras dura el per\u00edodo invernal, en el cual hay muy poco alimento disponible. Para mantener su temperatura corporal, ellos hacen uso de la grasa acumulada en etapas previas y del grueso pelaje del que se proveen durante el oto\u00f1o. Esto les da la posibilidad de esperar tranquilamente que pasen los fr\u00edos y en los primeros d\u00edas de primavera comienzan a salir y a reiniciar su actividad en el exterior.<br \/>\nA trav\u00e9s de estos ejemplos es posible apreciar que la modorra del invierno tiene su raz\u00f3n de ser y que los procesos de la naturaleza requieren de ciertas condiciones y de ciertos tiempos que no conviene tratar de acelerar. Validar los per\u00edodos de quietud como algo positivo es el primer paso para explorar con libertad el mundo interno y comenzar a hacer nuevos descubrimientos. Cada cierto tiempo es importante detenerse, hacer un alto en el camino, mirar la hoja de ruta, revisar nuestras creencias, conectarnos con los sentimientos m\u00e1s profundos, evaluar si hemos llegado a donde quer\u00edamos llegar.<br \/>\nEn este ejercicio resulta valioso tambi\u00e9n reconocer esa parte oculta de nosotros mismos \u2014la \u201csombra\u201d de Jung\u2014 para poder concebir la totalidad de lo que somos. El invierno del alma demuestra que no es posible saltarse ninguna etapa del proceso de autoconocimiento, por m\u00e1s dif\u00edcil que parezca. Es necesario experimentar lo que significa enfrentar la oscuridad, encandilarse con la luz, conocer la alegr\u00eda, el logro y la frustraci\u00f3n, para poder realizar plenamente nuestras potencialidades; y adem\u00e1s, para desarrollar la humildad, la empat\u00eda y la compasi\u00f3n, cualidades del m\u00e1s alto nivel en la evoluci\u00f3n humana. Entrar en el silencio para encontrarse con la paz interior genera un vac\u00edo indispensable para la acci\u00f3n de la creatividad y la imaginaci\u00f3n. En cambio, el aturdimiento que produce el bullicio impide escuchar, la saturaci\u00f3n de pensamientos dificulta crear y la sobrecarga emocional impide la conexi\u00f3n con el esp\u00edritu. Por eso, de vez en cuando es indispensable tomar distancia de la ansiedad cotidiana y, simplemente, darse un tiempo para escuchar el viento y contemplar caer la lluvia.<\/p>\n<p style=\"text-align: center;\"><strong>El colador de agua<\/strong><\/p>\n<p style=\"text-align: left;\">Cuento an\u00f3nimo suf\u00ed<\/p>\n<p style=\"text-align: left;\">Un grupo de devotos invit\u00f3 a un maestro de meditaci\u00f3n a la casa de uno de ellos para que los instruyera. El maestro dijo que deb\u00edan esforzarse por liberarse de reaccionar en demas\u00eda frente a los hechos de la vida diaria, por lograr una actitud de reverencia, y por adquirir la pr\u00e1ctica regular de un m\u00e9todo de meditaci\u00f3n que, a su vez, les explic\u00f3 en detalle. El objetivo era darse cuenta de que la vida divina est\u00e1 presente en todo. \u201cEs estar conscientes de esto no solo durante el per\u00edodo de meditaci\u00f3n, sino constantemente, en lo cotidiano. El proceso es como llenar un colador con agua.\u201d Luego, el maestro hizo una reverencia ante ellos y parti\u00f3.<br \/>\nEl peque\u00f1o grupo se despidi\u00f3 de \u00e9l y despu\u00e9s, uno de ellos se dirigi\u00f3 a los dem\u00e1s, echando chispas de frustraci\u00f3n. \u201cLo que nos dijo es como decirnos que nunca podremos lograrlo. \u00a1Llenar un colador con agua! \u00bfC\u00f3mo? Eso es lo que ocurre, \u00bfno? Al menos para m\u00ed. Escucho un serm\u00f3n, rezo, leo alg\u00fan libro sagrado, ayudo a mis vecinos con sus ni\u00f1os y ofrezco el m\u00e9rito a Dios, o algo por el estilo y despu\u00e9s me siento elevado. Mi car\u00e1cter mejora durante un tiempo&#8230; no me siento tan impaciente, ni hago tantos juicios sobre otras personas. Pero pronto el efecto se disipa, y vuelvo a ser el mismo que antes. Es como el agua en un colador, por supuesto. Y ahora \u00e9l nos dice que eso es todo.\u201d Siguieron reflexionando sobre la imagen del colador sin lograr ninguna soluci\u00f3n que lograra satisfacerlos a todos. Algunos pensaron que el maestro les dec\u00eda que las personas como ellos en este mundo solo pod\u00edan aspirar a una elevaci\u00f3n transitoria, otros creyeron que el maestro simplemente les estaba tomando el pelo. Incluso dijeron que tal vez se estar\u00eda refiriendo a algo en los cl\u00e1sicos que supon\u00eda que ellos sab\u00edan, buscaron, entonces, referencias sobre un colador en la literatura cl\u00e1sica, sin ning\u00fan \u00e9xito. Con el tiempo, el inter\u00e9s de todos se desvaneci\u00f3, excepto el de una mujer que decidi\u00f3 ir a ver al maestro. Entonces, \u00e9l le dio un colador y un taz\u00f3n, y fueron juntos a una playa cercana. All\u00ed parados sobre una roca y rodeados por las olas, le dijo: \u201cMu\u00e9strame c\u00f3mo llenas un colador con agua\u201d.<br \/>\nElla se inclin\u00f3, tom\u00f3 el colador con una mano y comenz\u00f3 a llenarlo con el taz\u00f3n, pero el agua apenas llegaba a cubrir la base del colador y luego se filtraba a trav\u00e9s de los agujeros \u201cCon la pr\u00e1ctica espiritual es lo mismo\u201d, dijo el maestro, \u201cmientras uno permanece de pie en la roca del Yo e intenta llenarla con cucharadas de conciencia divina. No es ese el modo de llenar un colador con agua, ni nuestra esencia con vida divina.\u201d \u201cEntonces, \u00bfc\u00f3mo se hace?\u201d, pregunt\u00f3 la mujer.<br \/>\nEl maestro tom\u00f3 el colador en sus manos y lo arroj\u00f3 lejos al mar. El colador flot\u00f3 unos instantes y despu\u00e9s se hundi\u00f3.<br \/>\n\u201cAhora est\u00e1 lleno de agua, y as\u00ed permanecer\u00e1\u201d, dijo el maestro. \u201cEse es el modo de llenar u n colador con agua, y es el modo de realizar la pr\u00e1ctica espiritual. No se logra vertiendo peque\u00f1as dosis de vida divina en la individualidad, sino arrojando la individualidad dentro del mar de la vida divina\u201d.<\/p>\n<p style=\"text-align: center;\">\n<button class=\"simplefavorite-button has-count\" data-postid=\"4950\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>La cueva Tal como hemos se\u00f1alado anteriormente, cuando el alma llega al invierno busca un espacio donde refugiarse, similar a [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":4956,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-4950","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/4950","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=4950"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/4950\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/4956"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=4950"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=4950"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=4950"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}