{"id":5813,"date":"2021-01-01T16:37:24","date_gmt":"2021-01-01T19:37:24","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=5813"},"modified":"2021-01-01T17:02:07","modified_gmt":"2021-01-01T20:02:07","slug":"la-llamada-del-alma","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/la-llamada-del-alma\/","title":{"rendered":"La Llamada del Alma .."},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Comprender el Sentido<\/strong><\/p>\n<p><strong>Se presenta una llamada\u00a0<\/strong><\/p>\n<p>\u00bfHay una sabidur\u00eda que lo contiene todo ? \u00bfhay alg\u00fan prop\u00f3sito en todo lo que sucede ? \u00bf Hay alguien ah\u00ed ?<\/p>\n<p>La respuesta es definitivamente s\u00ed&#8221;; s\u00ed, la vida es sabia. Todo lo que ocurre en la vida y en el cuerpo tiene sentido, y s\u00ed, hay alguien que siempre est\u00e1 aqu\u00ed y en quien puedes confiar ilimitadamente: tu alma. El alma nos env\u00eda sus mensajes en una mir\u00edada de formas, y para poder escucharla hay que comprender su mensaje, despertando un arte que hemos olvidado, el arte de escuchar la vida.<\/p>\n<p>Dominamos el arte de escuchar la vida cuando descubrimos el mensaje de los acontecimientos que se presentan en nuestro escenario, especialmente los que interpretamos como desagradables o contradictorios. Cuando escuchamos atentamente, encontramos el mensaje; cuando lo tomamos y lo incorporamos a nuestra vida, se convierte en un regalo.<\/p>\n<p>Es f\u00e1cil encontrar el regalo cuando el mensaje llega a trav\u00e9s de algo agradable, como por ejemplo cuando aparece la oportunidad que estabas esperando o cuando te enamoras y todo confluye para que la uni\u00f3n con esa persona se realice. En estos casos la situaci\u00f3n que se presenta es una se\u00f1al de que estamos alineados y es un invitaci\u00f3n a seguir adelante en esa misma direcci\u00f3n.<\/p>\n<p>Por el contrario, no es f\u00e1cil encontrar el regalo cuando se presenta a trav\u00e9s de un obst\u00e1culo en el escenario de la vida o de una enfermedad en el cuerpo. Sin embargo, son precisamente estas situaciones aparentemente adversas las que contienen los m\u00e1s valiosos y poderosos mensajes para guiar nuestro siguiente paso en el camino de vida. Recoger el mensaje al que se\u00f1alan estas situaciones nos despierta, nos libera de la circunstancia que nos hac\u00eda sufrir y tambi\u00e9n nos sana; y no s\u00f3lo puede sanar nuestro cuerpo f\u00edsico o nuestra propia vida, sino tambi\u00e9n nuestras relaciones personales, a nuestros ascendientes y a nuestros descendientes.<\/p>\n<p>Bienvenido al lenguaje del Alma, el arte de escuchar la vida y alinearse con sus mensajes. El lenguaje que usa el alma para comunicarse contigo es el de los s\u00edmbolos y las se\u00f1ales universales, no el lenguaje racional articulado, que es una convenci\u00f3n. Por tanto, la clave para escuchar lo que quiere decirnos el alma es entender su lenguaje. Todos tenemos la maravillosa capacidad de recibir el mensaje que el alma nos muestra, y la intenci\u00f3n de este momento es despertarla. Este momento nos mostrar\u00e1 c\u00f3mo convertirnos en artistas conscientes capaces de crear vida y cuerpo f\u00edsico, ambos como un reflejo de nuestro ser interior. Aprenderemos a descubrir el mensaje que hay detr\u00e1s de lo que nos ocurre, y vamos a desarrollar la capacidad de alinearte instant\u00e1neamente con \u00e9l para crear salud en tu cuerpo y plenitud en tu vida.<\/p>\n<p>De vez en cuando ocurre algo que irrumpe en lo cotidiano de forma inesperada, algo que no estaba previsto ni planificado. Si comparamos nuestra trayectoria en la vida con el rumbo de un velero navegando en mar abierto, el suceso que ha ocurrido representa un cambio repentino en la direcci\u00f3n del viento. Un buen navegante nota con facilidad los cambios de viento, y en concordancia con ellos, ajusta de inmediato las velas y el tim\u00f3n para enderezar su rumbo.<\/p>\n<p>Cuando lleguemos a comprender el lenguaje del alma, veremos que los sucesos que nos trae la vida contienen el impulso necesario para enderezar nuestra trayectoria vital.<\/p>\n<p>Es importante aclarar que &#8220;Vida &#8221; con la inicial en may\u00fascula, es sin\u00f3nimo de Unidad, Dios o Consciencia Divina en cualquiera de sus manifestaciones. En \u00faltimo t\u00e9rmino es la dimensi\u00f3n espiritual en cada uno de nosotros, es decir, lo que llamamos nuestra alma.<\/p>\n<p>El alma es nuestra consciencia de unidad con todo lo que nos rodea, es nuestra dimensi\u00f3n espiritual. Cada persona recibe su llamada a su singular manera y tambi\u00e9n en funci\u00f3n de sus creencias. Por ejemplo, si la percibe desde su interior, sentir\u00e1 que es su voz interior o que es su alma quien le habla; si la percibe como proveniente del exterior sentir\u00e1 que es la Consciencia Divina o la Vida quien le habla o le gu\u00eda. En cualquier caso, ya sea , a trav\u00e9s de las circunstancias de la vida o desde el interior del coraz\u00f3n, es siempre el alma quien nos est\u00e1 hablando con el fin de llevarnos a alinearnos con nuestra naturaleza espiritual.<\/p>\n<p>Cuando escuchamos\u00a0<em>El lenguaje del alma\u00a0<\/em>nos damos cuenta de que las situaciones imprevistas contienen claros mensajes para que hagamos un ajuste en el rumbo de nuestra vida. Si escuchamos y atendemos esta llamada experimentaremos\u00a0<em>una alineaci\u00f3n instant\u00e1nea,\u00a0<\/em>el viraje suceder\u00e1 de forma suave y amable y nos sentiremos bien a pesar del contratiempo. Si no atendemos la llamada y continuamos con el antiguo rumbo, el cambio de direcci\u00f3n habr\u00e1 de suceder m\u00e1s tarde, probablemente de forma m\u00e1s brusca o incluso dram\u00e1tica.<\/p>\n<p>La llamada del alma llega en tres niveles. El primer nivel nos da la oportunidad de alinearnos instant\u00e1neamente a trav\u00e9s de seguir nuestra voz interior, las corazonadas y tambi\u00e9n a trav\u00e9s de prestar atenci\u00f3n a los sue\u00f1os y las coincidencias en lo que percibimos como realidad externa, es decir, casualidades inesperadas que se presentan en el escenario donde transcurre nuestra vida. Llevado a lo cotidiano, esto implica escuchar a nuestra intuici\u00f3n y hacer caso al coraz\u00f3n, incluso a pesar de tener un plan preestablecido en otra direcci\u00f3n.<\/p>\n<p>Sino conseguimos alinearnos en el primer momento, la oportunidad se seguir\u00e1 presentando y llegaremos al segundo nivel que es el de &#8221; las llamadas suaves &#8221; . Estas se manifiestan en nuestra vida como contratiempos, obst\u00e1culos o dificultades, y , en nuestro cuerpo, a trav\u00e9s de sensaciones inc\u00f3modas. Cuando comprendemos\u00a0<em>el lenguaje del alma,<\/em> seguir su llamada se convierte en el arte de decir s\u00ed &#8221; a lo que la vida trae en cada momento. No s\u00f3lo a lo que nos gusta, sino a todo. Cuando no escuchemos, la llamada reaparecer\u00e1 m\u00e1s adelante, probablemente con mayor intensidad, para que finalmente alcancemos a comprender profundamente lo que est\u00e1 pasando. La forma m\u00e1s simple de estar alineado con el camino espiritual es abrazar lo que la vida nos presenta en cada momento. Cuando nos rendimos al fluir de la existencia, desaparece la resistencia y un ose entrega completamente a lo que surge.<\/p>\n<p>Imagina c\u00f3mo ser\u00eda la experiencia de un viaje o camino en el que uno dice &#8221; no &#8221; a cada paso, en un enfrentamiento continuo con lo que ocurre, chocando contra los obst\u00e1culos y nadando a contra corriente. Ahora imagina lo contrario, decir &#8221; s\u00ed &#8221; a tu pulsi\u00f3n y hacerte uno con la vida en cada paso. Puedes alinearte con esa pulsi\u00f3n o resistirte a ella. Al resistirte, se transforma en un impulso reprimido, se acumula y se hace m\u00e1s grande, y en la siguiente oportunidad irrumpir\u00e1 con m\u00e1s fuerza. Si uno niega o ignora esa pulsi\u00f3n de vida durante cierto tiempo, la llamada del alma pasa de suave a intensa.<\/p>\n<p>El tercer nivel corresponde a las &#8221; llamadas intensas &#8220;, que son las que transmiten poderosos mensajes a trav\u00e9s de s\u00edntomas f\u00edsicos, emocionales o enfermedades; tambi\u00e9n corresponden a acontecimientos que tienen la capacidad de variar dr\u00e1sticamente el rumbo de la vida. Dolores corporales, enfermedades, accidentes y tambi\u00e9n separaciones no deseadas son ejemplos de llamadas que apuntan a un ajuste en la trayectoria de vida. Lo que se puede calificar como una enfermedad seria o cr\u00f3nica es una llamada intensa del alma. Una enfermedad grave, si adem\u00e1s se percibe como una amenaza para la continuidad de la vida, es una llamada extrema del alma y apunta no s\u00f3lo a un simple ajuste en el tim\u00f3n, sino a un cambio radical de rumbo en el curso de la existencia. Y ese es precisamente el regalo que trae esa llamada extrema.<\/p>\n<p>Podemos preguntarnos por nuestro grado de escucha en este momento, porque no se trata de si el alma nos habla o no, sino de nuestra capacidad o voluntad de escuchar. \u00bf En qu\u00e9 nivel est\u00e1s ubicado? Est\u00e1s escuchando lo que sucede en el momento y te sientes a menudo alineado, o est\u00e1s en le nivel de las llamadas suaves y se suceden las adversidades o contrariedades en el escenario de tu vida ? En alg\u00fan momento quiz\u00e1 alcancemos el nivel de las llamadas intensas y el cuerpo f\u00edsico nos llame la atenci\u00f3n con dolores, s\u00edntomas variados o incluso con una enfermedad. No importa el nivel al que hayamos llegado si nos proponemos escuchar inmediatamente los mensajes o se\u00f1ales que nos proporciona el alma a trav\u00e9s de las circunstancias que se presentan. Bienvenido a\u00a0<em>El lenguaje del alma,\u00a0<\/em>que vas a aprender a escuchar y usar.<\/p>\n<p>Algo te ha llamado la atenci\u00f3n para leer este art\u00edculo. Quiz\u00e1s puedas reconocer el impulso de tomarlo como una llamada suave de la vida, ya que el alma nos est\u00e1 llamando continuamente. Bienvenido a la aventura que representa haber dicho s\u00ed &#8221; a esta llamada. La intenci\u00f3n de este espacio es ofrecer una gu\u00eda de viaje que te sirva para orientarte y para disfrutar el recorrido de la vida, siempre nuevo. Ahora ya est\u00e1s listo para dar el siguiente paso : el momento de experimentar ser uno con la vida. para m\u00ed es un honor acompa\u00f1arte.<\/p>\n<p><strong>Encuentra sentido a lo que est\u00e1 ocurriendo<\/strong><\/p>\n<p>Es posible que una situaci\u00f3n complicada est\u00e9 sucediendo en ahora en tu vida y que no te sea posible aceptarla y entregarte a ella. Aceptar significa abrir el coraz\u00f3n para que abrace todas las sensaciones que te despierta esta situaci\u00f3n. Entregarte significa escuchar interiormente y hacer lo que sientes que te toca hacer. Si no puedes aceptar lo que est\u00e1 pasando, integrarlo y abrir el coraz\u00f3n a lo que est\u00e1 ocurriendo es evidente que la vida te est\u00e1 empujando para que des un paso adelante en tu crecimiento o evoluci\u00f3n. Es como si tu forma de ver la vida se hubiera quedado peque\u00f1a, estrecha o anticuada para la situaci\u00f3n que se est\u00e1 produciendo. Esa forma de ver la vida, que tambi\u00e9n puedes llamar tu antiguo mundo o sistema de creencias, requiere un ajuste para adaptarse a la nueva situaci\u00f3n y crecer a trav\u00e9s de ella.<\/p>\n<p>Aunque parece que nos movemos hacia adelante por la vida, digiri\u00e9ndonos hacia las cosas que queremos, la realidad es que creamos y atraemos lo que aparece delante de nosotros. Cada situaci\u00f3n que se nos presenta es como si estuvi\u00e9ramos frente a un escenario que abre sus cortinas y nos muestra lo que hemos creado. Cualquiera sea la situaci\u00f3n que est\u00e9s viviendo, vas a dar un paso transformador en tu vida cuando descubras su prop\u00f3sito. Sea lo que sea que aparezca en tu escenario, contiene una invitaci\u00f3n del alma para evolucionar. Para que suceda esa evoluci\u00f3n, la clave es encontrar el sentido profundo de lo que est\u00e1 ocurriendo. Para encontrarlo puedes hacerte alguna de estas preguntas, las que sean m\u00e1s sugerentes para ti :<\/p>\n<ul>\n<li>\u00bfPara qu\u00e9 estoy viviendo esto ?<\/li>\n<li>\u00bfC\u00f3mo lo he creado internamente?<\/li>\n<li>\u00bfQu\u00e9 parte de m\u00ed se est\u00e1 reflejando exteriormente en esta situaci\u00f3n ?<\/li>\n<li>\u00bfQu\u00e9 parte de m\u00ed se qued\u00f3 anticuada y es el momento de renovarnos?<\/li>\n<li>\u00bfHacia d\u00f3nde apunta mi crecimiento o transformaci\u00f3n personal?<\/li>\n<li>\u00bfCu\u00e1l es el nuevo paso que me toca dar en la vida y c\u00f3mo lo doy&#8217;<\/li>\n<li>\u00bfCu\u00e1l es el regalo que me est\u00e1 reservado en \u00e9sta situaci\u00f3n ?<\/li>\n<li>\u00bfQu\u00e9 est\u00e1 aguardando que lo reciba?<\/li>\n<\/ul>\n<p>Despu\u00e9s de explorar estas preguntas, d\u00e1ndote un espacio de silencio para responderlas, es posible que el sentido que le dabas a esta situaci\u00f3n en tu vida haya cambiado. Cuando encuentres el prop\u00f3sito que hay detr\u00e1s de las circunstancias que est\u00e1s viviendo podr\u00e1s alinearte con la situaci\u00f3n y con el momento en una sola respiraci\u00f3n.<\/p>\n<p>Si ahora no aparece la respuesta a estas preguntas, no importa. Vas a aprender a encontrarla a trav\u00e9s de las pr\u00e1cticas a medida que vayamos avanzando. Finalmente, cuando el sentido sea pleno, la transformaci\u00f3n tendr\u00e1 lugar y la pregunta desaparecer\u00e1.<\/p>\n<p>El lenguaje del alma se\u00f1ala hacia el regalo que aparece en el escenario y que est\u00e1 esperando a ser recogido. Finalmente, el regalo tiene la capacidad de liberarnos de cualquier situaci\u00f3n para que podamos as\u00ed reconocernos como la pura conciencia que somos, y nos lleva a alinearnos con el paso que estamos dando en el camino.<\/p>\n<p>Este espacio est\u00e1 creado con la intenci\u00f3n de acompa\u00f1arte a encontrar el sentido o prop\u00f3sito que hay detr\u00e1s de lo que aparentemente est\u00e1 sucediendo, es decir, la verdad que hay detr\u00e1s o m\u00e1s all\u00e1 de tu opini\u00f3n o primera impresi\u00f3n sobre lo que est\u00e1 pasando. Lo que se observa en el mundo f\u00edsico es el resultado de un proceso creativo interior. Lo interesante no es el objeto o la situaci\u00f3n que se manifiesta, sino como uno la ha creado internamente. Este espacio est\u00e1 inspirado en el camino que te lleva a recoger el regalo definitivo, es decir, la liberaci\u00f3n, y en c\u00f3mo las circunstancias de la vida te conducen inexorablemente a encontrarla.<\/p>\n<p>Te garantizo que si buscas el sentido de las cosas que te pasan, definitivamente lo vas a encontrar. Es a eso a lo que me he dedicado durante m\u00e1s de veinte a\u00f1os de exploraci\u00f3n de las relaciones entre mente, cuerpo y alma: encontrar sentido a las vivencias que han ocurrido en el camino de otras personas y en el m\u00edo propio. Mi contribuci\u00f3n es mostrar y ayudar a recibir regalos en un espacio donde la salud conecta con la espiritualidad.<\/p>\n<p>En los pr\u00f3ximos art\u00edculos de los siguientes viernes exploraremos las claves para que puedas encontrar el sentido y el regalo de cualquier circunstancia por adversa, dolorosa o absurda que parezca. Dar\u00e9 continuos ejemplos de c\u00f3mo esto sucede para que te sirvan de inspiraci\u00f3n y de gu\u00eda. Encontrar el regalo de esos acontecimientos va a ser que tu experiencia de vida sea satisfactoria y plena. Lo que llamo liberaci\u00f3n est\u00e1 en la siguiente dimensi\u00f3n de la conciencia, a la que inevitablemente nos dirigimos en nuestro viaje por la vida.<\/p>\n<p>Feliz Comienzo de A\u00f1o !! \ud83d\ude42<\/p>\n<p>&nbsp;<\/p>\n<button class=\"simplefavorite-button has-count\" data-postid=\"5813\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>Comprender el Sentido Se presenta una llamada\u00a0 \u00bfHay una sabidur\u00eda que lo contiene todo ? \u00bfhay alg\u00fan prop\u00f3sito en todo [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":5925,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5813","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/5813","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=5813"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/5813\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/5925"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=5813"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=5813"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=5813"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}