{"id":5825,"date":"2020-12-27T19:08:40","date_gmt":"2020-12-27T22:08:40","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=5825"},"modified":"2020-12-31T11:08:40","modified_gmt":"2020-12-31T14:08:40","slug":"del-cielo-que-enferma-y-la-tierra-que-sana-constelaciones-familiares","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/del-cielo-que-enferma-y-la-tierra-que-sana-constelaciones-familiares\/","title":{"rendered":"Del Cielo que enferma y la Tierra que sana .. Constelaciones Familiares"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>DEL CIELO QUE ENFERMA Y LA TIERRA QUE SANA<\/strong><\/p>\n<p>Lo que aqu\u00ed se dice del cielo describe lo que en la familia y en la red familiar, como comunidades de personas unidas por el destino, conduce a enfermedades graves, a accidentes o al suicidio; y lo que se dice de la tierra pretende describir lo que, a veces, logra<br \/>\ndar otro rumbo a estas suertes.<br \/>\nEnfermedades graves o accidentes y suicidios en el seno de la familia o de la red familiar son desencadenados por procesos que se entrelazan con im\u00e1genes del cielo, de sufrimiento y de expiaci\u00f3n en lugar de otras personas, de un reencuentro despu\u00e9s de la muerte, y de inmortalidad personal. Estas im\u00e1genes seducen a un pensar y desear y actuar m\u00e1gicos, en los que el enfermo o el moribundo cree que, a trav\u00e9s del sufrimiento deliberadamente aceptado, puede redimir a otros de su sufrimiento, aunque este forme parte de su destino.<br \/>\nLas observaciones y las comprensiones del trabajo con constelaciones familiares que se describen a continuaci\u00f3n ayudan a desenmascarar tales ideas enfermizas para superarlas de una forma sanadora.<\/p>\n<p>A esta comunidad de personas unida por el destino \u2013en la que obran estas ideas fatales\u2013 pertenecen los hermanos, los padres y sus hermanos, los abuelos, a veces alg\u00fan bisabuelo, y todos los que hicieron sitio para uno de estos miembros de la familia.<br \/>\nEntre los que hicieron sitio cuentan los c\u00f3nyuges anteriores de los padres y de los abuelos, o las relaciones comparables a un matrimonio, por ejemplo, los novios anteriores.<br \/>\nAsimismo, forman parte todos aquellos por cuya desaparici\u00f3n o desgracia otros pudieron acceder a este grupo o tuvieron alguna ventaja en otro \u00e1mbito. En esta comunidad unida por el destino todos se hallan atados a todos. Donde m\u00e1s fuerza cobra el v\u00ednculo creado por el destino es de hijos a padres, entre hermanos y entre marido y mujer. Asimismo, se crea un v\u00ednculo especial desde las personas que entraron en el sistema posteriormente hacia aquellos que hicieron sitio para ellos, especialmente si estos tuvieron una suerte dif\u00edcil: por ejemplo, el v\u00ednculo que se desarrolla entre los hijos de un segundo<br \/>\nmatrimonio de un hombre hacia su primera mujer, que muri\u00f3 de parto. El v\u00ednculo es menos fuerte de padres a hijos, o de aquellos que hicieron sitio a los que les siguieron en ese lugar: por ejemplo, de una novia anterior del marido a su mujer posterior.<\/p>\n<p>Por este v\u00ednculo, pues, los posteriores y m\u00e1s d\u00e9biles pretenden sujetar a los anteriores y m\u00e1s fuertes para que estos no se vayan, o, si ya se fueron, desean seguirles. Por este v\u00ednculo, los aventajados pretenden asemejarse a los que sufren la desventaja.<br \/>\nAs\u00ed pues, los hijos sanos quieren parecerse a sus padres enfermos, y los peque\u00f1os, inocentes, a los grandes, culpables. Por este v\u00ednculo, los sanos se sienten responsables de los enfermos; los inocentes, de los culpables; los felices, de los desdichados, y los vivos, de los muertos.<br \/>\nPor tanto, los que reciben la ventaja est\u00e1n dispuestos a arriesgar y a ofrecer tanto su salud como su inocencia, su vida como su felicidad por la salud, la inocencia, la vida y la felicidad de otros, ya que albergan la esperanza de poder asegurar o salvar la vida y la felicidad de otros miembros de esta comunidad, renunciando a su propia vida y a su propia felicidad. Y esperan poder recuperar y restablecer la vida y la felicidad de otros, aunque ya<br \/>\nest\u00e9n perdidas.<br \/>\nAs\u00ed pues, del v\u00ednculo y del amor que este v\u00ednculo comporta, en la comunidad de la familia y de la red familiar nace la necesidad imperiosa de llegar a un equilibrio entre la ventaja de unos y la desventaja de otros, entre la inocencia y la felicidad de unos y la culpa y la desdicha de otros, entre la salud de unos y la enfermedad de otros, y entre la vida de unos y la muerte de otros. Es esta necesidad la que lleva a una persona a desear tambi\u00e9n la desdicha donde otro miembro de su sistema fue desdichado; donde otro cay\u00f3 enfermo o contrajo una culpa, una persona sana o inocente tambi\u00e9n enferma o se hace culpable, y, donde una persona querida muri\u00f3, otra persona pr\u00f3xima a ella desea morir tambi\u00e9n.<br \/>\nEn el seno de esta comunidad tan estrechamente unida por el destino, el v\u00ednculo y la necesidad de compensaci\u00f3n llevan a la participaci\u00f3n y a la imitaci\u00f3n de la culpa y de la enfermedad de otros, de su destino y de su muerte. Asimismo, se intenta pagar la salvaci\u00f3n de otros con la desgracia propia; la curaci\u00f3n de otros, con la propia enfermedad; la inocencia de otros, con la culpa o la expiaci\u00f3n propia, y la vida de otros, con la propia muerte.<\/p>\n<p><strong>La enfermedad sigue al alma<\/strong><br \/>\nDado que esta necesidad de semejanza y compensaci\u00f3n anhela la enfermedad y la muerte, por as\u00ed decirlo, la enfermedad sigue al alma. Por tanto, aparte de la ayuda m\u00e9dica en un sentido m\u00e1s estricto, la sanaci\u00f3n requiere tambi\u00e9n la ayuda de personas que conocen las necesidades del alma, bien sea que el m\u00e9dico mismo re\u00fana ambos aspectos, bien sea que otra persona complemente el trabajo m\u00e9dico, atendiendo la psique. Ahora bien, mientras el m\u00e9dico se esfuerza por curar la enfermedad a trav\u00e9s de su tratamiento, el psicoterapeuta m\u00e1s bien se retiene, ya que, lleno de asombro, se halla ante fuerzas con las que le parecer\u00eda<br \/>\narrogante competir. As\u00ed pues, intenta cambiar un destino fatal estando en sinton\u00eda con estas fuerzas, convirti\u00e9ndose m\u00e1s bien en su aliado que en su enemigo. A este respecto quisiera referir un ejemplo:<\/p>\n<p><strong>\u00abMejor que sea yo que t\u00fa\u00bb<\/strong><br \/>\nDurante una hipnoterapia, una joven paciente de esclerosis m\u00faltiple se vio a s\u00ed misma de ni\u00f1a, arrodillada delante de la cama de su madre paral\u00edtica, formulando interiormente este prop\u00f3sito: \u00abQuerida Mam\u00e1, mejor que sea yo que t\u00fa\u00bb.<br \/>\nPara los dem\u00e1s participantes del grupo fue una experiencia profundamente conmovedora ver cu\u00e1nto una hija ama a sus padres, y la mujer joven se sent\u00eda en paz consigo misma y con su suerte. Una participante, sin embargo, no pudo soportar ese amor dispuesto a tomar sobre s\u00ed enfermedades, dolores e incluso la muerte por el bien de la madre. Le dijo al terapeuta:<br \/>\n\u2013\u00a1Deseo de todo coraz\u00f3n que puedas ayudarle!<br \/>\nEl terapeuta se qued\u00f3 perplejo; para \u00e9l fue como si lo hubiera deshecho todo, ya que c\u00f3mo es posible que alguien trate el amor de la hija como si fuera algo malo. \u00bfAcaso no herir\u00eda el alma de la hija, agravando su sufrimiento en vez de aliviarlo? \u00bfAcaso la hija no guardar\u00eda a\u00fan m\u00e1s celosamente su amor a la madre, aferr\u00e1ndose a\u00fan m\u00e1s apasionadamente a su esperanza y a su prop\u00f3sito, surgidos en aquel momento, de salvar a la madre amada a<br \/>\ntrav\u00e9s de su propio sufrimiento?<br \/>\nA\u00fan quisiera presentar otro ejemplo m\u00e1s. En un grupo, una mujer joven, que tambi\u00e9n padec\u00eda de esclerosis m\u00faltiple, configur\u00f3 su familia de origen y la trama relacional que reinaba en su seno. As\u00ed pues, hab\u00eda la madre y, a su izquierda, el padre. Enfrente de ellos se encontraba la paciente, como hija mayor; a su izquierda, el hermano siguiente, que muri\u00f3 de un paro card\u00edaco a los 14 a\u00f1os, y, a la izquierda de este, el hermano m\u00e1s joven.<br \/>\nPartiendo de esta constelaci\u00f3n, el terapeuta le pidi\u00f3 al representante del hermano muerto que saliera por la puerta, lo cual, en una constelaci\u00f3n familiar, significa morir. En el momento en el que sali\u00f3 por la puerta, la cara de la hija se ilumin\u00f3 de golpe, y tambi\u00e9n la madre se sinti\u00f3 mucho mejor. Despu\u00e9s, el terapeuta envi\u00f3 fuera al hermano menor, y, despu\u00e9s, al padre, porque hab\u00eda notado que tambi\u00e9n ellos tend\u00edan a salir del sistema. En cuanto hab\u00edan salido todos los hombres \u2013lo cual significa que todos estaban muertos\u2013, la madre se enderez\u00f3 con un gesto triunfante, quedando claro que era ella la que se sab\u00eda presa de la muerte \u2013cualquiera que fuera el motivo\u2013, y tambi\u00e9n, cu\u00e1n aliviada se sent\u00eda al ver que otros estaban dispuestos a tomar sobre s\u00ed la muerte en lugar de ella.<br \/>\nA continuaci\u00f3n, el terapeuta volvi\u00f3 a llamar a los hombres, y, en su lugar, envi\u00f3 fuera a la madre. De repente, todos se sintieron librados de la obligaci\u00f3n de participar en el destino de la madre, y se encontraban bien.<br \/>\nEl terapeuta, sin embargo, sospechaba que tambi\u00e9n la esclerosis m\u00faltiple de la hija podr\u00eda estar relacionada con el hecho de que la madre se sintiera obligada a morir. Por tanto, hizo entrar nuevamente a la madre, la puso al lado del padre, y llev\u00f3 a la hija al lado de ella. A continuaci\u00f3n, le dijo a la hija que mirara a la madre con amor y que le dijera a los ojos y a la cara: \u00abMam\u00e1, yo lo hago en tu lugar\u00bb. Al pronunciar estas palabras, la cliente se puso radiante, y el significado y la finalidad de su enfermedad quedaron claros para todos los presentes.<\/p>\n<p>Experiencia relatada por Bert Hellinger<\/p>\n<button class=\"simplefavorite-button has-count\" data-postid=\"5825\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>DEL CIELO QUE ENFERMA Y LA TIERRA QUE SANA Lo que aqu\u00ed se dice del cielo describe lo que en [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":5307,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-5825","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/5825","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=5825"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/5825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/5307"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=5825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=5825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=5825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}