{"id":7495,"date":"2021-03-10T17:57:09","date_gmt":"2021-03-10T20:57:09","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=7495"},"modified":"2021-03-10T18:53:09","modified_gmt":"2021-03-10T21:53:09","slug":"el-desafio-de-sostener-nuestra-prosperidad","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/el-desafio-de-sostener-nuestra-prosperidad\/","title":{"rendered":"El Desaf\u00edo de sostener nuestra Prosperidad"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Prosperidad Integral, un Enfoque para enriquecer tu Vida<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center;\"><em><strong>La buena relaci\u00f3n con el dinero es la base de una relaci\u00f3n arm\u00f3nica con el mundo <\/strong><\/em><\/p>\n<p>\u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 \u00a0 <em><strong>\u00a0Beatriz Goldberg Psic\u00f3loga Argentina<\/strong><\/em><\/p>\n<p>La Prosperidad Integral explica discernir que podemos aprender a generar sostenidamente dinero mientras cultivamos un estado de bienestar, salud, alegr\u00eda, generosidad y crecimiento en nuestra vida. Desde este concepto hol\u00edstico, podemos transformar el dinero en una bendici\u00f3n para compartir con otras personas.<\/p>\n<p>Dinero y desarrollo emocional son los conceptos excluyentes y antagonistas; por el contrario, componen una sociedad complementaria y s\u00f3lida que nos permite desarrollar en plenitud y consciencia a fin de disfrutar y compartir sus beneficios con quienes nos rodean. Al respecto, millones de personas suelen considerar que el \u00e9xito de su prosperidad monetaria estriba en c\u00f3mo ganar y administrar eficazmente su dinero. Si bien es cierto que generar y manejar adecuadamente el dinero es muy importante, existen otros aspectos en que podr\u00edan contribuir a nuestra plenitud. Saber disfrutar y compartir nuestro dinero son los otros dos aspectos complementarios de ganar y administrar.<\/p>\n<p>La prosperidad se compone de cinco pilares requiere de nuestra atenci\u00f3n, observaci\u00f3n y dedicaci\u00f3n a fin de crear y sostener un estado de plenitud, armon\u00eda y bienestar en nuestra vida.<\/p>\n<p style=\"text-align: center;\"><strong>El Desaf\u00edo de sostener nuestra Prosperidad<\/strong><\/p>\n<p>Ganar dinero es tan importante es tan importante como sostener un estado de prosperidad. Millones de personas tienen dificultades marcadas para generar el sustento que les permite vivir c\u00f3modamente. Otras tantas son muy capaces de generar dinero, pero no pueden sostenerlo en el tiempo. A lo largo de mis a\u00f1os de profesi\u00f3n me ha tocado atender numerosos casos de profesionales y vendedores que consegu\u00edan ganar dinero por rachas, pero irremediablemente fracasaban a la hora de mantener ese ritmo de prosperidad en sus vidas. Detr\u00e1s de ese sube y baja en sus ingresos monetarios, subyac\u00edan razones psicol\u00f3gicas que les imped\u00edan mantener un estado de continuidad en sus ingresos. Es importante desarrollar la capacidad de mantener un ingreso a lo largo del tiempo.<\/p>\n<p>Miles de personas de frustran y deprimen debido a que intentan sostener un estilo de vida basado en sus ganancias monetarias fluctuantes. Es as\u00ed que pueden consumir productos de lujo, asociarse en clubes exclusivos, tener dos autos y enviar a sus hijos a colegios caros. A ellos mismos les puede gustar aparentar una imagen de prosperidad que puede no condecir con sus ingresos monetarios, lo cual los lleva a mediano plazo a endeudarse y angustiarse irremediablemente.<\/p>\n<p>Ganar dinero es importante, pero sostener y aumentar ese ingreso a lo largo del tiempo es una cualidad a desarrollar y entrenar. Llegado este punto, podr\u00edamos formularnos una pregunta : \u00bf La prosperidad implica poder mantener en el tiempo lo que ganamos, para ir acrecent\u00e1ndolo ? Al respecto podemos decir, en t\u00e9rminos generales, que una persona, empresa o pa\u00eds es pr\u00f3spero, cuando sostiene un crecimiento a lo largo del tiempo. Cuando no hay continuidad en las actitudes de conductas que nos conducen hacia un estado de prosperidad, podemos tener altibajos que van minando gradualmente nuestra autoestima y bienestar. Y ello impacta, entre otras cosas, en nuestra capacidad de generar dinero.<\/p>\n<p style=\"text-align: left;\"><strong>La Belleza del Compromiso contigo mismo<\/strong><\/p>\n<p>La palabra\u00a0 &#8221; compromiso &#8221; tiene varios significados, entre ellos la responsabilidad u obligaci\u00f3n que se contrae. Compromiso es una palabra muy bella con connotaciones profundas que van m\u00e1s all\u00e1 de lo explicado en los diversos diccionarios de la lengua castellana. El compromiso refiere a un pacto o acuerdo que podemos realizar con nosotros mismos a fin de crecer y prosperar en nuestra vida. Toda persona que ha logrado cierto nivel de \u00e9xito en su empleo, profesi\u00f3n, emprendimiento o negocio y lo ha mantenido en el tiempo ha desarrollado un nivel de compromiso consigo mismo.<\/p>\n<p>El compromiso involucra situaciones que pueden colocarnos en riesgo, pero conlleva la posibilidad de aprender y crecer, de asumir responsabilidades con nosotros y los dem\u00e1s. A su vez, implica un compromiso que asumimos con nosotros y otras personas en determinados temas ( pareja, trabajo, salidas recreativas, etc). Cuanto m\u00e1s honramos un compromiso que nos ayuda a crecer y evolucionar, obtenemos mayores niveles de confianza, apertura y seguridad en nuestra vida. Aunque tambi\u00e9n el compromiso puede ser segmentado y traernos problemas. Por ejemplo, existen personas que consiguen comprometerse con su trabajo pero descuidan su aspecto emocional y vincular. Hay quienes concentran su energ\u00eda en la actividad intelectual, y otros que focalizan su inter\u00e9s en placeres f\u00edsicos. Cada uno de nosotros, consciente o inconscientemente puede haberse comprometido con alg\u00fan \u00e1rea o aspecto de su personalidad. Tambi\u00e9n pueden existir dificultades para comprometernos con \u00e1reas de nuestra vida que podr\u00edan generarnos mayores niveles de bienestar, plenitud y crecimiento. Algunos de los pacientes que he atendido manifestaban problemas para comprometerse en una relaci\u00f3n profunda de pareja. Otras trabajan duramente, pero descuidan su salud y recreaci\u00f3n. Cuanto m\u00e1s compromisos generamos con las \u00e1reas relevantes de nuestra vida estamos contribuyendo a crear prosperidad y abundancia integral.<\/p>\n<p>Miles de personas manifiestan a diario su deseo de ganar m\u00e1s dinero o lograr un lugar de trabajo creativo y placentero; sin embargo, evidencian conflictos internos que les impiden comprometerse con aquellas conductas y actitudes que les permitir\u00edan avanzar en sus metas. Uno de los conceptos que m\u00e1s enfatizo en la Diplomatura de Inteligencia Espiritual para L\u00edderes es el valor de construir &#8221; H\u00e1bitos de Poder &#8221; que impliquen aquellas peque\u00f1as acciones que repetimos a diario y que contribuyen a aumentar nuestra vitalidad, salud, motivaci\u00f3n y confianza interna. Por ejemplo, la pr\u00e1ctica de deportes, agradecer a Dios al despertarnos por un nuevo d\u00eda, practicar meditaci\u00f3n o yoga, compartir con amigos, son algunos de los m\u00faltiples ejercicios que podemos realizar con cierta frecuencia y que potencian nuestro compromiso interior.<\/p>\n<p>Si deseas lograr ciertos niveles de prosperidad en tu vida, precisas construir h\u00e1bitos de poder que te ayuden a crear un estado de salud, potencia y bienestar. Desde ah\u00ed ser\u00e1 m\u00e1s sencillo y accesible desarrollar un compromiso real y factible con tus metas. Esto tambi\u00e9n te ayudar\u00e1 a construir un compromiso contigo mismo a fin de que logres un estado de prosperidad integral, tambi\u00e9n te ayudar\u00e1 a lograr un mayor grado de conciencia en ti para reconocer las dificultades y limitaciones que est\u00e1n impidi\u00e9ndote vivir con plenitud y abundancia.<\/p>\n<blockquote class=\"wp-embedded-content\" data-secret=\"YAl2tppQJ2\"><p><a href=\"https:\/\/pachapulai.com.ar\/encuentros\/formacion\/inteligencia-espiritual-para-lideres\/\">Inteligencia Espiritual para L\u00edderes<\/a><\/p><\/blockquote>\n<p><iframe class=\"wp-embedded-content lazyload\" sandbox=\"allow-scripts\" security=\"restricted\" style=\"position: absolute; clip: rect(1px, 1px, 1px, 1px);\" title=\"\u00abInteligencia Espiritual para L\u00edderes\u00bb \u2014 Pacha Pulai | Encuentros\" data-src=\"https:\/\/pachapulai.com.ar\/encuentros\/formacion\/inteligencia-espiritual-para-lideres\/embed\/#?secret=YAl2tppQJ2\" data-secret=\"YAl2tppQJ2\" width=\"600\" height=\"338\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<button class=\"simplefavorite-button has-count\" data-postid=\"7495\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>Prosperidad Integral, un Enfoque para enriquecer tu Vida &nbsp; La buena relaci\u00f3n con el dinero es la base de una [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":7501,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-7495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/7495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=7495"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/7495\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/7501"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=7495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=7495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=7495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}