{"id":8210,"date":"2021-04-23T17:18:19","date_gmt":"2021-04-23T20:18:19","guid":{"rendered":"https:\/\/pachapulai.com.ar\/encuentros\/?p=8210"},"modified":"2021-04-23T17:18:19","modified_gmt":"2021-04-23T20:18:19","slug":"nuestra-identidad-gastronomica","status":"publish","type":"post","link":"https:\/\/pachapulai.com.ar\/encuentros\/nuestra-identidad-gastronomica\/","title":{"rendered":"Nuestra Identidad Gastron\u00f3mica"},"content":{"rendered":"<p style=\"text-align: center;\"><strong>Nuestra Identidad Gastron\u00f3mica<\/strong><\/p>\n<p>En la Argentina, la gastronom\u00eda tiene una gran influencia inmigratoria, con prevalencia de las comidas italianas y espa\u00f1olas, principalmente, y de la carne, y como ya vimos, un s\u00edmbolo nacional de gran reconocimiento internacional por su calidad. De todas formas, en los \u00faltimos a\u00f1os se han abierto m\u00e1s restaurantes de diferentes etnias y fusiones, como la peruano-japonesa (nikkei), lo que da la posibilidad de explorar el mundo y sus culturas de una manera entretenida, placentera, y sin necesidad de viajar miles de kil\u00f3metros.<\/p>\n<p>Comer bien, tiene que ver con la calidad de los productos, la elaboraci\u00f3n y el servicio. No hace falta ir al restaurante de moda o al m\u00e1s caro; podemos encontrar platos incre\u00edbles en nuestra casa, en un bodeg\u00f3n o en un barrio, porque lujo no es sin\u00f3nimo de calidad. De hecho, si nos preguntamos cu\u00e1l es la comida que m\u00e1s nos gusta, posiblemente respondamos que es la que nos prepara nuestra madre. No hay ning\u00fan restaurante del mundo que la iguale, \u00bfverdad ?<\/p>\n<p><strong>La Comida Emociona<\/strong><\/p>\n<p>La comida tiene una gran carga emocional, genera sentimientos y recuerdos. Es una manera de &#8220;viajar&#8221; hacia el pasado cercano o hacia nuestra infancia. M\u00e1s de una persona cuando prueba unos ravioles de la abuela, porque estaban hechos con mucho amor, un sentimiento clave para lograr el mejor plato.<\/p>\n<p>Massimo Bottura, chef italiano, lo explica en la primera temporada del documental <em>Chef\u00b4s table, de David Gelb, de Netflix :\u00a0<\/em>En mis diversas creaciones, ver\u00e1n que intento llevarlos a ese momento, en el que uno era ni\u00f1o&#8221;.<\/p>\n<p><strong>La cocina marca Tendencia<\/strong><\/p>\n<p>En la actualidad, la gente comparte su vida privada en las redes sociales. Las fotograf\u00edas de lo platos de comidas y de restaurantes son muy populares en Twitter, Facebook e Instagram, y esto se debe a que la comida tiene una conexi\u00f3n autom\u00e1tica con el placer.<\/p>\n<p>La demostraci\u00f3n del impacto que tienen las im\u00e1genes gastron\u00f3micas es la cantidad de publicaciones etiquetadas en diferentes\u00a0<em>hashtag\u00a0<\/em>(palabra clave para identificar un tema) en Instagram. Realic\u00e9 una b\u00fasqueda en esta red social y encontr\u00e9 191.669.953 de fotograf\u00edas publicadas con la palabra food (comida), 87.587.801 con foodporn (comida pornogr\u00e1fica) y 2.778.888 publicaciones con la etiqueta comida.<\/p>\n<p>La gastronom\u00eda es lo que marca la tendencia. Est\u00e1 de moda, es cool, est\u00e1 bien visto comer bien. Antes, eran la ropa y los dise\u00f1adores como Coco Channel, Ralph Loren, Carolina Herrera los que impon\u00edan la moda. Pero ahora los cocineros son verdaderos rock star, como los argentinos Mauro Colagreco, Francis Mallmann y Fernando Trocca; el italiano Massimo Bottura o el Peruano Virgilio Mart\u00ednez Veliz.<\/p>\n<p>Adem\u00e1s de cocinar de una manera extraordinaria, estos cocineros reconocidos entre los mejores del mundo son investigadores, porque analizan la calidad y diversidad de los productos para conseguir la combinaci\u00f3n qu\u00edmica exacta y encontrar el sabor perfecto. Tambi\u00e9n son artistas, por las presentaciones que logran en sus platos. Para que un plato sea apetitoso, la apariencia tambi\u00e9n es importante, porque todo entra en nuestro cuerpo a trav\u00e9s de los ojos.<\/p>\n<p><strong>Los osos panda son golosos .. y vos ?\u00a0<\/strong><\/p>\n<p>Un grupo de investigadores descubri\u00f3 que a\u00a0 los osos pandas gigantes les encanta el az\u00facar. Estudiaron este tipo de mam\u00edferos en China durante seis meses y descubrieron que, aunque su comida de base es la ca\u00f1a de bamb\u00fa, tienen una debilidad por el az\u00facar. Este gusto est\u00e1 determinado por los genes. Al estudiar su ADN demostraron que tienen variantes funcionales iguales a las de los seres humanos en los genes TAS1R2, los\u00a0 responsables de detectar el az\u00facar que consumimos.<\/p>\n<p>En realidad, la mayor\u00eda de los seres humanos desde los inicios de nuestra evoluci\u00f3n tenemos una preferencia por lo dulce. Un alimento o bebida dulce es la mejor fuente de energ\u00eda para nuestro cuerpo, ya que tiene mayor cantidad de hidratos de carbono ( az\u00facar) .<\/p>\n<p>Aunque no seamos conscientes de eso, en esta conducta tambi\u00e9n hay informaci\u00f3n gen\u00e9tica. El sabor dulce resulta m\u00e1s seguro, pues, desde la \u00e9poca de los or\u00edgenes del hombre moderno la detecci\u00f3n de un sabor amargo en una planta o vegetal estaba asociado con la posibilidad de una toxina o veneno y, por lo general, se dejaba de lado hasta que se comprobara su seguridad alimentaria. Tarea dif\u00edcil en esos tiempos, ya que a aquel a quien le tocaba hacerlo deb\u00eda poner en riesgo la vida.<\/p>\n<p>Si lo que preferimos es comer torta, chocolates, caramelos y helados, y tenemos esta variante gen\u00e9tica, vamos a correr mayor riesgo de desarrollar caries\u00a0 dentales y obesidad. Por eso, aunque todos sepamos que los dulces son una debilidad y ahora adem\u00e1s hayamos descubierto que nuestra tendencia es una conducta milenaria por la supervivencia, intentemos comerlos con moderaci\u00f3n.<\/p>\n<p><strong>Te gusta m\u00e1s el sabor amargo ?\u00a0 Tu genes definen tu gusto preferido<\/strong><\/p>\n<p>Si tenemos que decidir entre comer una torta o un sandwich, seguramente en un milisegundo podremos elegir. Y , si alguien nos pregunta si preferimos dulce o salado, tambi\u00e9n responderemos instant\u00e1neamente. Es que, aunque no lo creas, nuestros genes participan en la identificaci\u00f3n de nuestros gustos.<\/p>\n<p>Hay un gen llamado TAS2R38 que determina c\u00f3mo una persona percibe el sabor amargo. Cuando la comida entra en la boca, se estimula la papila gustativa en la lengua, los nervios transmiten la informaci\u00f3n al cerebro y \u00e9ste interpreta el nivel de amargor. Seg\u00fan su variante gen\u00e9tica, cuando una persona come o toma algo amargo, define lo que siente como mucho, un poco o nada amargo.<\/p>\n<p>La manera de comprobar la preferencia por este sabor es utilizar el compuesto qu\u00edmico artificial llamado Feniltiocarbamida (PTC). Sustancias similares al PTC est\u00e1n presentes en alimentos como el br\u00f3coli, los esp\u00e1rragos, el repollo, la lechuga, las endivias, los alcauciles, entre tantos otros; y en bebidas como el caf\u00e9, el whisky escoc\u00e9s, la cerveza negra y algunos vinos. La capacidad de la PTC para identificar un sabor amargo var\u00eda entre diferentes poblaciones, pero en promedio est\u00e1 presente en el 75% de los individuos, mientras que un 25% no lo detecta. Estas variaciones no deber\u00edan llamarnos tanto la atenci\u00f3n, ya que as\u00ed como hay dalt\u00f3nicos tambi\u00e9n hay quienes no pueden percibir ciertos sabores.<\/p>\n<p>En le mundo animal, las especies herb\u00edvoras, como los caballos, las vacas y los ciervos, tienen menor cantidad de genes que detectan el sabor amargo. De esta manera tienen mayor posibilidad de alimentarse: si tuvieran una gran sensibilidad para detectar y rechazar este sabor, tendr\u00edan menor cantidad de alimentos disponibles.<\/p>\n<p>La intensidad con la cual se detecta el sabor amargo depende entonces, de nuestra composici\u00f3n gen\u00e9tica, y, como vimos, determina que algunas personas no puedan tomar el caf\u00e9 sin az\u00facar o edulcorante porque les resulta muy fuerte, mientras que otras lo prefieren amargo.<\/p>\n<p>Quienes tienen gran sensibilidad para detectar el sabor amargo comen un 25% menos de vegetales; as\u00ed, la gen\u00e9tica determina una modificaci\u00f3n de su dieta. Pero , por otro lado, estas personas se ven beneficiadas en su salud, pues corren menos riesgo de fumar, ya que no soportan el sabor del tabaco.<\/p>\n<p>&nbsp;<\/p>\n<p>Y a vos ? qu\u00e9 te gusta ? \ud83d\ude0a<\/p>\n<p>&nbsp;<\/p>\n<p><iframe title=\"BOMBONES DE QUAKER SIN MANTECA\" width=\"1080\" height=\"608\" data-src=\"https:\/\/www.youtube.com\/embed\/kTwMQQzMAmc?feature=oembed&#038;enablejsapi=1&#038;origin=https:\/\/pachapulai.com.ar\"  allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture\" allowfullscreen src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" class=\"lazyload\" data-load-mode=\"1\"><\/iframe><\/p>\n<p>&nbsp;<\/p>\n<p><img decoding=\"async\" class=\"alignnone  wp-image-3058 aligncenter lazyload\" data-src=\"https:\/\/pachapulai.com.ar\/encuentros\/wp-content\/uploads\/version-horizontal-300x84.png\" alt=\"Pacha Pulai\" width=\"264\" height=\"74\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 264px; --smush-placeholder-aspect-ratio: 264\/74;\" \/><\/p>\n<button class=\"simplefavorite-button has-count\" data-postid=\"8210\" data-siteid=\"1\" data-groupid=\"1\" data-favoritecount=\"0\" style=\"box-shadow:none;-webkit-box-shadow:none;-moz-box-shadow:none;background-color:#ffffff;border-color:#989fca;color:#3f3b9b;\"><i class=\"sf-icon-love\"> <\/i><span class=\"simplefavorite-button-count\" style=\"color:#3f3b9b;\">0<\/span><\/button>","protected":false},"excerpt":{"rendered":"<p>Nuestra Identidad Gastron\u00f3mica En la Argentina, la gastronom\u00eda tiene una gran influencia inmigratoria, con prevalencia de las comidas italianas y [&hellip;]<\/p>\n","protected":false},"author":19,"featured_media":8137,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[1],"tags":[],"class_list":["post-8210","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-reflexiones"],"_links":{"self":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/8210","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/users\/19"}],"replies":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/comments?post=8210"}],"version-history":[{"count":0,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/posts\/8210\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media\/8137"}],"wp:attachment":[{"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/media?parent=8210"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/categories?post=8210"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/pachapulai.com.ar\/encuentros\/wp-json\/wp\/v2\/tags?post=8210"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}